{"id":2984,"date":"2019-01-03T23:02:35","date_gmt":"2019-01-03T20:02:35","guid":{"rendered":"https:\/\/alnajmi.net\/portal\/?page_id=2984"},"modified":"2023-03-18T01:38:25","modified_gmt":"2023-03-17T22:38:25","slug":"fat3","status":"publish","type":"page","link":"https:\/\/alnajmi.net\/portal\/fatawas\/fat3\/","title":{"rendered":"\u0641\u062a\u0627\u0648\u0649 \u0639\u0642\u062f\u064a\u0629"},"content":{"rendered":"[mhc_section admin_label=&#8221;\u0642\u0633\u0645&#8221; fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221; transparent_background=&#8221;off&#8221; gradient_background=&#8221;off&#8221; background_color=&#8221;#f0ece0&#8243; gradient_style=&#8221;horizontal&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; video_pause=&#8221;off&#8221; allow_advanced_padding=&#8221;off&#8221; remove_padding=&#8221;off&#8221; force_fullwidth=&#8221;off&#8221; column_paddings=&#8221;padding-0pct&#8221; column_match_heights=&#8221;off&#8221; separator_top=&#8221;off&#8221; separator_bottom=&#8221;off&#8221;][mhc_row admin_label=&#8221;\u0635\u0641&#8221;][mhc_column type=&#8221;4_4&#8243;][mhc_text admin_label=&#8221;\u0646\u0635&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;right&#8221; animation=&#8221;off&#8221;]\n<h1><strong>\u0641\u062a\u0627\u0648\u0649 \u0639\u0642\u062f\u064a\u0629<\/strong><\/h1>\n<p>&nbsp;<\/p>\n\n<table id=\"tablepress-53\" class=\"tablepress tablepress-id-53 tablepress-responsive\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">\u0645<\/th><th class=\"column-2\">\u0627\u0644\u0639\u0646\u0648\u0627\u0646<\/th><th class=\"column-3\">\u0627\u0633\u062a\u0645\u0627\u0639<\/th><th class=\"column-4\">\u062a\u062d\u0645\u064a\u0644<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">\u0639\u0642\u0648\u0628\u0629 \u062a\u0627\u0631\u0643 \u0627\u0644\u0639\u0645\u0644<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445915e70.43121976\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445915e70.43121976','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed1.mp3','80','false');show_hide('play','6a04d445915e70.43121976');\" \/><input type=\"button\"  id=\"btnstop_6a04d445915e70.43121976\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445915e70.43121976','','80','false');show_hide('stop','6a04d445915e70.43121976');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed1.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">\u0642\u0648\u0644 \u0645\u0646 \u0642\u0627\u0644 \u0623\u0646\u0651\u064e \u0627\u0644\u062e\u0648\u0627\u0631\u062c \u0645\u0646 \u0623\u0647\u0644 \u0627\u0644\u0646\u0627\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445925d55.70530534\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445925d55.70530534','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed2.mp3','80','false');show_hide('play','6a04d445925d55.70530534');\" \/><input type=\"button\"  id=\"btnstop_6a04d445925d55.70530534\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445925d55.70530534','','80','false');show_hide('stop','6a04d445925d55.70530534');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed2.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">\u0623\u062e\u0630 \u0627\u0644\u062c\u0646\u0633\u064a\u0629 \u0627\u0644\u0643\u0627\u0641\u0631\u0629 \u0627\u0644\u062a\u064a \u062a\u062d\u0643\u0645 \u0628\u0627\u0644\u0642\u0648\u0627\u0646\u064a\u0646 \u0627\u0644\u0648\u0636\u0639\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459351d5.95988639\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459351d5.95988639','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed3.mp3','80','false');show_hide('play','6a04d4459351d5.95988639');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459351d5.95988639\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459351d5.95988639','','80','false');show_hide('stop','6a04d4459351d5.95988639');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed3.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">\u0627\u0644\u0627\u0633\u062a\u0647\u0632\u0627\u0621 \u0628\u0627\u0644\u062f\u064a\u0646 \u0648\u0623\u0647\u0644\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445943865.08666339\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445943865.08666339','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed4.mp3','80','false');show_hide('play','6a04d445943865.08666339');\" \/><input type=\"button\"  id=\"btnstop_6a04d445943865.08666339\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445943865.08666339','','80','false');show_hide('stop','6a04d445943865.08666339');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed4.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639 \u0648\u0645\u0646 \u064a\u062f\u0627\u0641\u0639 \u0639\u0646\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459523d2.18529375\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459523d2.18529375','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed5.mp3','80','false');show_hide('play','6a04d4459523d2.18529375');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459523d2.18529375\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459523d2.18529375','','80','false');show_hide('stop','6a04d4459523d2.18529375');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed5.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">\u0627\u0644\u0623\u0645\u0648\u0631 \u0627\u0644\u062a\u064a \u064a\u0647\u062c\u0631 \u0641\u064a\u0647\u0627 \u0627\u0644\u0645\u0628\u062a\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445962063.09374133\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445962063.09374133','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed6.mp3','80','false');show_hide('play','6a04d445962063.09374133');\" \/><input type=\"button\"  id=\"btnstop_6a04d445962063.09374133\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445962063.09374133','','80','false');show_hide('stop','6a04d445962063.09374133');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed6.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">\u0639\u062f\u0645 \u062c\u0648\u0627\u0632 \u0627\u0644\u0627\u0633\u062a\u063a\u0641\u0627\u0631 \u0644\u0644\u0643\u0641\u0627\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445971da7.73910614\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445971da7.73910614','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed7.mp3','80','false');show_hide('play','6a04d445971da7.73910614');\" \/><input type=\"button\"  id=\"btnstop_6a04d445971da7.73910614\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445971da7.73910614','','80','false');show_hide('stop','6a04d445971da7.73910614');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed7.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0635\u0648\u064a\u0631 \u0627\u0644\u0641\u0648\u062a\u063a\u0631\u0627\u0641\u064a \u0644\u0630\u0648\u0627\u062a \u0627\u0644\u0623\u0631\u0648\u0627\u062d<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44597f1b6.82168356\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44597f1b6.82168356','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed8.mp3','80','false');show_hide('play','6a04d44597f1b6.82168356');\" \/><input type=\"button\"  id=\"btnstop_6a04d44597f1b6.82168356\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44597f1b6.82168356','','80','false');show_hide('stop','6a04d44597f1b6.82168356');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed8.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">\u0628\u064a\u0639 \u0648\u0634\u0631\u0627\u0621 \u0623\u0634\u0631\u0637\u0629 \u0627\u0644\u062d\u0632\u0628\u064a\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44598dc78.76799169\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44598dc78.76799169','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed9.mp3','80','false');show_hide('play','6a04d44598dc78.76799169');\" \/><input type=\"button\"  id=\"btnstop_6a04d44598dc78.76799169\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44598dc78.76799169','','80','false');show_hide('stop','6a04d44598dc78.76799169');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed9.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">\u0645\u0631\u062c\u0626\u0629 \u0627\u0644\u0641\u0642\u0647\u0627\u0621 \u062e\u0644\u0627\u0641\u0647\u0645 \u0641\u064a \u0623\u0639\u0645\u0627\u0644 \u0627\u0644\u062c\u0648\u0627\u0631\u062d<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44599c2e5.50460282\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44599c2e5.50460282','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed10.mp3','80','false');show_hide('play','6a04d44599c2e5.50460282');\" \/><input type=\"button\"  id=\"btnstop_6a04d44599c2e5.50460282\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44599c2e5.50460282','','80','false');show_hide('stop','6a04d44599c2e5.50460282');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed10.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">\u0645\u0631\u062c\u0626\u0629 \u0627\u0644\u0641\u0642\u0647\u0627\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459aa0b8.92574081\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459aa0b8.92574081','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed11.mp3','80','false');show_hide('play','6a04d4459aa0b8.92574081');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459aa0b8.92574081\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459aa0b8.92574081','','80','false');show_hide('stop','6a04d4459aa0b8.92574081');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed11.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">\u0627\u0644\u0623\u0646\u0627\u0634\u064a\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629 \u0635\u0648\u0641\u064a\u0629 \u0648\u0627\u0644\u062d\u0630\u0631 \u0645\u0646 \u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0635\u0648\u0641\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459b78f9.43681807\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459b78f9.43681807','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed12.mp3','80','false');show_hide('play','6a04d4459b78f9.43681807');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459b78f9.43681807\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459b78f9.43681807','','80','false');show_hide('stop','6a04d4459b78f9.43681807');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed12.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0632\u0639\u0645 \u0623\u0646\u0651\u064e \u0627\u0644\u0645\u0638\u0627\u0647\u0631\u0627\u062a \u0644\u064a\u0633\u062a \u0645\u0646 \u0628\u0627\u0628 \u0627\u0644\u0639\u0628\u0627\u062f\u0627\u062a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459c91d7.45027143\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459c91d7.45027143','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed13.mp3','80','false');show_hide('play','6a04d4459c91d7.45027143');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459c91d7.45027143\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459c91d7.45027143','','80','false');show_hide('stop','6a04d4459c91d7.45027143');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed13.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u0645\u0644\u062d\u062f \u0648\u0627\u0644\u0645\u0634\u0631\u0643<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459d8aa6.37383525\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459d8aa6.37383525','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed14.mp3','80','false');show_hide('play','6a04d4459d8aa6.37383525');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459d8aa6.37383525\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459d8aa6.37383525','','80','false');show_hide('stop','6a04d4459d8aa6.37383525');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed14.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">\u0627\u0644\u0646\u0635\u064a\u062d\u0629 \u0642\u0628\u0644 \u0627\u0644\u0647\u062c\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459e46a7.48133448\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459e46a7.48133448','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed15.mp3','80','false');show_hide('play','6a04d4459e46a7.48133448');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459e46a7.48133448\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459e46a7.48133448','','80','false');show_hide('stop','6a04d4459e46a7.48133448');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed15.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">\u0627\u0644\u0646\u0647\u064a \u0639\u0646 \u0645\u0646\u0627\u0638\u0631\u0629 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4459f2bd6.79775309\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4459f2bd6.79775309','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed16.mp3','80','false');show_hide('play','6a04d4459f2bd6.79775309');\" \/><input type=\"button\"  id=\"btnstop_6a04d4459f2bd6.79775309\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4459f2bd6.79775309','','80','false');show_hide('stop','6a04d4459f2bd6.79775309');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed16.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">\u0627\u0646\u0643\u0627\u0631 \u0627\u0644\u0645\u0633\u062d \u0639\u0644\u0649 \u0627\u0644\u062e\u0641\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445a841b7.70485439\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445a841b7.70485439','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed17.mp3','80','false');show_hide('play','6a04d445a841b7.70485439');\" \/><input type=\"button\"  id=\"btnstop_6a04d445a841b7.70485439\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445a841b7.70485439','','80','false');show_hide('stop','6a04d445a841b7.70485439');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed17.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">\u062a\u0635\u0648\u064a\u0631 \u0630\u0648\u0627\u062a \u0627\u0644\u0623\u0631\u0648\u0627\u062d<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445a95278.22733767\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445a95278.22733767','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed18.mp3','80','false');show_hide('play','6a04d445a95278.22733767');\" \/><input type=\"button\"  id=\"btnstop_6a04d445a95278.22733767\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445a95278.22733767','','80','false');show_hide('stop','6a04d445a95278.22733767');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed18.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">\u0645\u062d\u0645\u062f \u062d\u0633\u0627\u0646 \u0648\u0627\u0644\u062d\u0630\u0631 \u0645\u0646 \u0633\u0645\u0627\u0639 \u0623\u0634\u0631\u0637\u0629 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445aa2da0.38366345\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445aa2da0.38366345','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed19.mp3','80','false');show_hide('play','6a04d445aa2da0.38366345');\" \/><input type=\"button\"  id=\"btnstop_6a04d445aa2da0.38366345\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445aa2da0.38366345','','80','false');show_hide('stop','6a04d445aa2da0.38366345');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed19.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">\u0645\u0646 \u064a\u062f\u0627\u0641\u0639 \u0639\u0646 \u0641\u0627\u0644\u062d \u0627\u0644\u062d\u0631\u0628\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ab0b59.49551937\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ab0b59.49551937','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed20.mp3','80','false');show_hide('play','6a04d445ab0b59.49551937');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ab0b59.49551937\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ab0b59.49551937','','80','false');show_hide('stop','6a04d445ab0b59.49551937');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed20.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">\u0627\u0644\u0647\u062c\u0631\u0629 \u0645\u0646 \u0628\u0644\u0627\u062f \u0627\u0644\u0643\u0641\u0631 \u0625\u0644\u0649 \u0628\u0644\u0627\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445abd1e4.66511424\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445abd1e4.66511424','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed21.mp3','80','false');show_hide('play','6a04d445abd1e4.66511424');\" \/><input type=\"button\"  id=\"btnstop_6a04d445abd1e4.66511424\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445abd1e4.66511424','','80','false');show_hide('stop','6a04d445abd1e4.66511424');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed21.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">\u0627\u0644\u062a\u062d\u0630\u064a\u0631 \u0645\u0646 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639 \u0648\u0623\u0641\u0639\u0627\u0644\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ac9b27.30386826\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ac9b27.30386826','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed22.mp3','80','false');show_hide('play','6a04d445ac9b27.30386826');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ac9b27.30386826\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ac9b27.30386826','','80','false');show_hide('stop','6a04d445ac9b27.30386826');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed22.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">\u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u062d\u062c\u0629 \u0641\u064a \u062a\u0643\u0641\u064a\u0631 \u0627\u0644\u0645\u0639\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ad6985.22198488\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ad6985.22198488','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed23.mp3','80','false');show_hide('play','6a04d445ad6985.22198488');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ad6985.22198488\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ad6985.22198488','','80','false');show_hide('stop','6a04d445ad6985.22198488');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed23.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">\u0627\u0644\u0643\u0644\u0627\u0645 \u0641\u064a \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639 \u0644\u064a\u0633 \u0645\u0646 \u0627\u0644\u063a\u064a\u0628\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ae5fd4.66731232\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ae5fd4.66731232','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed24.mp3','80','false');show_hide('play','6a04d445ae5fd4.66731232');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ae5fd4.66731232\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ae5fd4.66731232','','80','false');show_hide('stop','6a04d445ae5fd4.66731232');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed24.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">\u0645\u0646 \u062c\u0627\u0644\u0633 \u0627\u0644\u062d\u0632\u0628\u064a\u064a\u0646 \u0627\u0644\u0645\u0628\u062a\u062f\u0639\u064a\u0646 \u0623\u0644\u062d\u0642 \u0628\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445af3d58.46181276\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445af3d58.46181276','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed25.mp3','80','false');show_hide('play','6a04d445af3d58.46181276');\" \/><input type=\"button\"  id=\"btnstop_6a04d445af3d58.46181276\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445af3d58.46181276','','80','false');show_hide('stop','6a04d445af3d58.46181276');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed25.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">\u0633\u0644\u0641\u064a \u064a\u062c\u0627\u0644\u0633 \u0627\u0644\u062d\u0632\u0628\u064a\u064a\u0646 \u0648\u064a\u062a\u0639\u0627\u0648\u0646 \u0645\u0639\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b039e2.67501975\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b039e2.67501975','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed26.mp3','80','false');show_hide('play','6a04d445b039e2.67501975');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b039e2.67501975\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b039e2.67501975','','80','false');show_hide('stop','6a04d445b039e2.67501975');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed26.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">27<\/td><td class=\"column-2\">\u0627\u0644\u0623\u0646\u0627\u0634\u064a\u062f \u0627\u0644\u0635\u0648\u0641\u064a\u0629 \u0648\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u0623\u062c\u0627\u0632\u0647\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b116c6.28442458\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b116c6.28442458','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed27.mp3','80','false');show_hide('play','6a04d445b116c6.28442458');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b116c6.28442458\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b116c6.28442458','','80','false');show_hide('stop','6a04d445b116c6.28442458');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed27.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">\u0627\u0644\u062a\u062d\u0630\u064a\u0631 \u0645\u0646 \u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0628\u0627\u0637\u0644\u0629 \u0648\u0623\u0646\u0651\u064e \u0627\u0644\u0639\u0628\u0631\u0629 \u0641\u064a \u0627\u0644\u062c\u0645\u0639\u064a\u0627\u062a \u0628\u0627\u0644\u0642\u0627\u0626\u0645\u064a\u0646 \u0639\u0644\u064a\u0647\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b1f237.33416258\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b1f237.33416258','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed28.mp3','80','false');show_hide('play','6a04d445b1f237.33416258');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b1f237.33416258\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b1f237.33416258','','80','false');show_hide('stop','6a04d445b1f237.33416258');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed28.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0635\u0631\u064a\u062d \u0628\u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629 \u0627\u0644\u0635\u062d\u064a\u062d\u0629 \u0641\u064a \u0627\u0644\u0625\u0645\u062a\u062d\u0627\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b2cc76.85418219\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b2cc76.85418219','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed29.mp3','80','false');show_hide('play','6a04d445b2cc76.85418219');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b2cc76.85418219\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b2cc76.85418219','','80','false');show_hide('stop','6a04d445b2cc76.85418219');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed29.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0648\u0627\u0644\u0645\u0646\u0647\u062c<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b394c9.00455041\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b394c9.00455041','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed30.mp3','80','false');show_hide('play','6a04d445b394c9.00455041');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b394c9.00455041\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b394c9.00455041','','80','false');show_hide('stop','6a04d445b394c9.00455041');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed30.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">\u0646\u0635\u064a\u062d\u0629 \u0645\u0646 \u0648\u0642\u0639 \u0641\u064a \u0627\u0644\u0628\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b467b9.98376596\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b467b9.98376596','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed31.mp3','80','false');show_hide('play','6a04d445b467b9.98376596');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b467b9.98376596\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b467b9.98376596','','80','false');show_hide('stop','6a04d445b467b9.98376596');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed31.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">32<\/td><td class=\"column-2\">\u0627\u0644\u0637\u0639\u0646 \u0648\u0627\u0644\u062a\u062c\u0631\u064a\u062d \u0644\u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639 \u0648\u0645\u0646 \u062a\u0639\u0627\u0637\u0641 \u0645\u0639\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b55512.45071283\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b55512.45071283','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed32.mp3','80','false');show_hide('play','6a04d445b55512.45071283');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b55512.45071283\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b55512.45071283','','80','false');show_hide('stop','6a04d445b55512.45071283');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed32.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">33<\/td><td class=\"column-2\">\u0623\u0643\u0644 \u0630\u0628\u0627\u0626\u062d \u0639\u0644\u0645\u0627\u0621 \u0627\u0644\u0634\u064a\u0639\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b65242.96431633\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b65242.96431633','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed33.mp3','80','false');show_hide('play','6a04d445b65242.96431633');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b65242.96431633\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b65242.96431633','','80','false');show_hide('stop','6a04d445b65242.96431633');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed33.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\">\u0627\u0644\u0625\u0633\u062a\u0645\u0631\u0627\u0631 \u0641\u064a \u0645\u062c\u0627\u0644\u0633\u0629 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b72561.56658541\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b72561.56658541','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed34.mp3','80','false');show_hide('play','6a04d445b72561.56658541');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b72561.56658541\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b72561.56658541','','80','false');show_hide('stop','6a04d445b72561.56658541');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed34.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">35<\/td><td class=\"column-2\">\u0625\u062b\u0628\u0627\u062a \u0635\u0641\u0629 \u0627\u0644\u0633\u0645\u0639 \u0644\u0644\u0647 \u0628\u062f\u0648\u0646 \u062a\u0643\u064a\u064a\u0641<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b80ed8.69736053\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b80ed8.69736053','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed35.mp3','80','false');show_hide('play','6a04d445b80ed8.69736053');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b80ed8.69736053\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b80ed8.69736053','','80','false');show_hide('stop','6a04d445b80ed8.69736053');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed35.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\">\u0627\u0644\u0645\u0638\u0627\u0647\u0631\u0627\u062a \u0636\u062f \u0627\u0644\u0643\u0641\u0627\u0631 \u0644\u064a\u0633\u062a \u0645\u0646 \u0627\u0644\u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0634\u0631\u0639\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b8e671.62981119\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b8e671.62981119','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed36.mp3','80','false');show_hide('play','6a04d445b8e671.62981119');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b8e671.62981119\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b8e671.62981119','','80','false');show_hide('stop','6a04d445b8e671.62981119');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed36.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">37<\/td><td class=\"column-2\">\u0643\u064a\u0641 \u0623\u062f\u0627\u0641\u0639 \u0627\u0644\u0631\u064a\u0627\u0621 \u0639\u0646 \u0646\u0641\u0633\u064a \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445b9e017.97592733\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445b9e017.97592733','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed37.mp3','80','false');show_hide('play','6a04d445b9e017.97592733');\" \/><input type=\"button\"  id=\"btnstop_6a04d445b9e017.97592733\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445b9e017.97592733','','80','false');show_hide('stop','6a04d445b9e017.97592733');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed37.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u0646\u0628\u063a\u064a \u0627\u0646\u062a\u0642\u0627\u062f \u0645\u0646 \u0630\u0643\u0631 \u0622\u062b\u0627\u0631 \u0627\u0644\u0633\u0644\u0641<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c0a4c3.29165356\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c0a4c3.29165356','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed38.mp3','80','false');show_hide('play','6a04d445c0a4c3.29165356');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c0a4c3.29165356\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c0a4c3.29165356','','80','false');show_hide('stop','6a04d445c0a4c3.29165356');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed38.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">39<\/td><td class=\"column-2\">\u0645\u0646 \u0627\u0644\u063a\u0644\u0648 \u0627\u0639\u062a\u0642\u0627\u062f \u0627\u0644\u0639\u0635\u0645\u0629 \u0644\u0622\u0644 \u0628\u064a\u062a \u0627\u0644\u0646\u0628\u064a \u0635\u0644\u0649 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c1fd97.58689337\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c1fd97.58689337','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed39.mp3','80','false');show_hide('play','6a04d445c1fd97.58689337');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c1fd97.58689337\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c1fd97.58689337','','80','false');show_hide('stop','6a04d445c1fd97.58689337');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed39.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0631\u0636\u064a \u0634\u0639\u0627\u0631 \u064a\u0637\u0644\u0642 \u0639\u0644\u0649 \u0627\u0644\u0635\u062d\u0627\u0628\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c2d893.52233346\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c2d893.52233346','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed40.mp3','80','false');show_hide('play','6a04d445c2d893.52233346');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c2d893.52233346\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c2d893.52233346','','80','false');show_hide('stop','6a04d445c2d893.52233346');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed40.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">41<\/td><td class=\"column-2\">\u062f\u0639\u0648\u0649 \u0627\u062c\u062a\u0645\u0627\u0639 \u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0636\u0627\u0644\u0629 \u0639\u0644\u0649 \u0627\u0644\u0643\u062a\u0627\u0628 \u0648\u0627\u0644\u0633\u0646\u0629 \u0642\u0648\u0644 \u0628\u0627\u0637\u0644<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c3ba55.53559342\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c3ba55.53559342','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed41.mp3','80','false');show_hide('play','6a04d445c3ba55.53559342');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c3ba55.53559342\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c3ba55.53559342','','80','false');show_hide('stop','6a04d445c3ba55.53559342');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed41.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">42<\/td><td class=\"column-2\">\u062a\u0632\u0643\u064a\u0629 \u0633\u0644\u064a\u0645 \u0627\u0644\u0647\u0644\u0627\u0644\u064a \u0648\u0639\u0644\u064a \u062d\u0633\u0646 \u0627\u0644\u062d\u0644\u0628\u064a \u0644\u0644\u0645\u0623\u0631\u0628\u064a \u0648\u0627\u0644\u0645\u063a\u0631\u0627\u0648\u064a \u0627\u0644\u062a\u0643\u0641\u064a\u0631\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c49335.43469100\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c49335.43469100','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed42.mp3','80','false');show_hide('play','6a04d445c49335.43469100');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c49335.43469100\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c49335.43469100','','80','false');show_hide('stop','6a04d445c49335.43469100');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed42.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">43<\/td><td class=\"column-2\">\u0627\u0644\u062a\u062b\u0628\u062a \u0641\u064a \u0627\u0644\u062d\u0643\u0645 \u0639\u0644\u0649 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u062d\u062a\u0649 \u062a\u0638\u0647\u0631 \u062d\u0632\u0628\u064a\u062a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c56db4.84711733\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c56db4.84711733','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed43.mp3','80','false');show_hide('play','6a04d445c56db4.84711733');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c56db4.84711733\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c56db4.84711733','','80','false');show_hide('stop','6a04d445c56db4.84711733');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed43.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">44<\/td><td class=\"column-2\">\u0627\u0644\u062f\u0639\u0648\u0629 \u0625\u0644\u0649 \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0635\u062d\u064a\u062d\u0629 \u0623\u0648\u0644\u0627\u064b<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c653b1.08009238\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c653b1.08009238','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed44.mp3','80','false');show_hide('play','6a04d445c653b1.08009238');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c653b1.08009238\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c653b1.08009238','','80','false');show_hide('stop','6a04d445c653b1.08009238');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed44.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">45<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u062d\u0645\u062f \u0633\u0631\u0648\u0631 \u0648\u0623\u0645\u062b\u0627\u0644\u0647 \u0641\u064a \u0627\u0633\u062a\u0647\u0632\u0627\u0626\u0647\u0645 \u0628\u0643\u062a\u0628 \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0648\u062e\u0637\u0628\u0647\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c72c40.29268796\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c72c40.29268796','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed45.mp3','80','false');show_hide('play','6a04d445c72c40.29268796');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c72c40.29268796\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c72c40.29268796','','80','false');show_hide('stop','6a04d445c72c40.29268796');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed45.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">46<\/td><td class=\"column-2\">\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0623\u0631\u0643\u0627\u0646 \u0627\u0644\u0625\u064a\u0645\u0627\u0646 \u0648\u0634\u0639\u0628\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c7f748.07835068\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c7f748.07835068','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed46.mp3','80','false');show_hide('play','6a04d445c7f748.07835068');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c7f748.07835068\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c7f748.07835068','','80','false');show_hide('stop','6a04d445c7f748.07835068');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed46.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">47<\/td><td class=\"column-2\">\u0627\u0644\u0646\u0647\u064a \u0639\u0646 \u0627\u0644\u0648\u0642\u0648\u0641 \u0644\u0644\u0623\u0634\u062e\u0627\u0635 \u0645\u0646 \u0628\u0627\u0628 \u0627\u0644\u062a\u0639\u0638\u064a\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c8d162.27781743\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c8d162.27781743','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed47.mp3','80','false');show_hide('play','6a04d445c8d162.27781743');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c8d162.27781743\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c8d162.27781743','','80','false');show_hide('stop','6a04d445c8d162.27781743');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed47.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">48<\/td><td class=\"column-2\">\u0646\u062d\u0646 \u0645\u0644\u0632\u0645\u0648\u0646 \u0628\u0627\u062a\u0628\u0627\u0639 \u0627\u0644\u0633\u0644\u0641 \u0627\u0644\u0635\u0627\u0644\u062d \u0631\u0636\u0648\u0627\u0646 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445c9bc39.10263768\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445c9bc39.10263768','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed48.mp3','80','false');show_hide('play','6a04d445c9bc39.10263768');\" \/><input type=\"button\"  id=\"btnstop_6a04d445c9bc39.10263768\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445c9bc39.10263768','','80','false');show_hide('stop','6a04d445c9bc39.10263768');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed48.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">49<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0635\u0648\u064a\u0631 \u0643\u0644\u0647 \u062d\u0631\u0627\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445cab2e2.63592249\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445cab2e2.63592249','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed49.mp3','80','false');show_hide('play','6a04d445cab2e2.63592249');\" \/><input type=\"button\"  id=\"btnstop_6a04d445cab2e2.63592249\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445cab2e2.63592249','','80','false');show_hide('stop','6a04d445cab2e2.63592249');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed49.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">50<\/td><td class=\"column-2\">\u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0625\u0646\u062a\u062d\u0627\u0631\u064a\u0629 \u0636\u062f \u0627\u0644\u064a\u0647\u0648\u062f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445cbe620.43609614\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445cbe620.43609614','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed50.mp3','80','false');show_hide('play','6a04d445cbe620.43609614');\" \/><input type=\"button\"  id=\"btnstop_6a04d445cbe620.43609614\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445cbe620.43609614','','80','false');show_hide('stop','6a04d445cbe620.43609614');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed50.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">51<\/td><td class=\"column-2\">\u0627\u0644\u0643\u0641\u0631 \u0646\u0648\u0639\u0627\u0646 \u0643\u0641\u0631 \u0627\u0639\u062a\u0642\u0627\u062f\u064a \u0648\u0643\u0641\u0631 \u0639\u0645\u0644\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ccf968.73920275\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ccf968.73920275','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed51.mp3','80','false');show_hide('play','6a04d445ccf968.73920275');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ccf968.73920275\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ccf968.73920275','','80','false');show_hide('stop','6a04d445ccf968.73920275');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed51.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">52<\/td><td class=\"column-2\">\u0643\u062a\u0627\u0628 \u0645\u0646\u0647\u062c \u0627\u0644\u0623\u0646\u0628\u064a\u0627\u0621 \u0641\u064a \u0627\u0644\u062f\u0639\u0648\u0629 \u0625\u0644\u0649 \u0627\u0644\u0644\u0647 \u0644\u0644\u0634\u064a\u062e \u0631\u0628\u064a\u0639 \u0627\u0644\u0645\u062f\u062e\u0644\u064a \u062d\u0641\u0638\u0647 \u0627\u0644\u0644\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ce5cf1.68727262\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ce5cf1.68727262','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed52.mp3','80','false');show_hide('play','6a04d445ce5cf1.68727262');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ce5cf1.68727262\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ce5cf1.68727262','','80','false');show_hide('stop','6a04d445ce5cf1.68727262');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed52.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">53<\/td><td class=\"column-2\">\u0645\u0646 \u0643\u0627\u0646 \u0639\u0644\u0649 \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u0646\u0628\u064a \u0635\u0644\u0649 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645 \u0648\u0623\u0635\u062d\u0627\u0628\u0647 \u0641\u0647\u0648 \u0627\u0644\u0646\u0627\u062c\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445cf5ca6.18885879\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445cf5ca6.18885879','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed53.mp3','80','false');show_hide('play','6a04d445cf5ca6.18885879');\" \/><input type=\"button\"  id=\"btnstop_6a04d445cf5ca6.18885879\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445cf5ca6.18885879','','80','false');show_hide('stop','6a04d445cf5ca6.18885879');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed53.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">54<\/td><td class=\"column-2\">\u0648\u062c\u0648\u0628 \u062a\u062d\u0630\u064a\u0631 \u0627\u0644\u0622\u0628\u0627\u0621 \u0644\u0623\u0628\u0646\u0627\u0626\u0647\u0645 \u0645\u0646 \u0627\u0644\u062d\u0632\u0628\u064a\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445d06d74.64488457\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445d06d74.64488457','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed54.mp3','80','false');show_hide('play','6a04d445d06d74.64488457');\" \/><input type=\"button\"  id=\"btnstop_6a04d445d06d74.64488457\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445d06d74.64488457','','80','false');show_hide('stop','6a04d445d06d74.64488457');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed54.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\">\u0639\u064a\u0633\u0649 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u062a\u0648\u0641\u0627\u0647 \u0627\u0644\u0644\u0647 \u0648\u0631\u0641\u0639\u0647 \u0625\u0644\u064a\u0647 \u0648\u0647\u0648 \u0646\u0627\u0626\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445d922d6.81259619\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445d922d6.81259619','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed55.mp3','80','false');show_hide('play','6a04d445d922d6.81259619');\" \/><input type=\"button\"  id=\"btnstop_6a04d445d922d6.81259619\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445d922d6.81259619','','80','false');show_hide('stop','6a04d445d922d6.81259619');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed55.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">56<\/td><td class=\"column-2\">\u0627\u0644\u0625\u062e\u0628\u0627\u0631 \u0639\u0646 \u0623\u062d\u0648\u0627\u0644 \u0627\u0644\u0645\u0639\u0630\u0628\u064a\u0646 \u0648\u0627\u0644\u0645\u0646\u0639\u0645\u064a\u0646 \u060c \u0648\u0623\u0646 \u0627\u0644\u0639\u0630\u0627\u0628 \u0648\u0627\u0644\u0646\u0639\u064a\u0645 \u0641\u064a \u0627\u0644\u0628\u0631\u0632\u062e \u064a\u0643\u0648\u0646 \u0639\u0644\u0649 \u0627\u0644\u0631\u0648\u062d \u0648\u0627\u0644\u062c\u0633\u062f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445da3f87.14654592\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445da3f87.14654592','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed56.mp3','80','false');show_hide('play','6a04d445da3f87.14654592');\" \/><input type=\"button\"  id=\"btnstop_6a04d445da3f87.14654592\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445da3f87.14654592','','80','false');show_hide('stop','6a04d445da3f87.14654592');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed56.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">57<\/td><td class=\"column-2\">\u0627\u0644\u0625\u0645\u0631\u0629 \u0641\u064a \u0627\u0644\u0633\u0641\u0631 \u062a\u0646\u062a\u0647\u064a \u0628\u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0628\u0644\u062f \u0627\u0644\u0625\u0642\u0627\u0645\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445db8dd8.15674654\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445db8dd8.15674654','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed57.mp3','80','false');show_hide('play','6a04d445db8dd8.15674654');\" \/><input type=\"button\"  id=\"btnstop_6a04d445db8dd8.15674654\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445db8dd8.15674654','','80','false');show_hide('stop','6a04d445db8dd8.15674654');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed57.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">58<\/td><td class=\"column-2\">\u0627\u0644\u062d\u062c \u064a\u0642\u062f\u0645 \u0639\u0644\u0649 \u0627\u0644\u0647\u062c\u0631\u0629 \u0625\u0644\u0649 \u0628\u0639\u0636 \u0627\u0644\u0628\u0644\u062f\u0627\u0646 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u062d\u0627\u0631\u0628 \u0641\u064a\u0647\u0627 \u0634\u0639\u0627\u0626\u0631 \u0627\u0644\u0644\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445dc80a8.50739970\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445dc80a8.50739970','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed58.mp3','80','false');show_hide('play','6a04d445dc80a8.50739970');\" \/><input type=\"button\"  id=\"btnstop_6a04d445dc80a8.50739970\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445dc80a8.50739970','','80','false');show_hide('stop','6a04d445dc80a8.50739970');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed58.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">59<\/td><td class=\"column-2\">\u0637\u0627\u0644\u0628 \u0627\u0644\u0639\u0644\u0645 \u0627\u0644\u0645\u0628\u062a\u062f\u064a \u0644\u0627 \u064a\u0641\u062a\u064a \u0648\u0644\u0627 \u064a\u062a\u0635\u062f\u0631 \u0644\u0644\u0641\u062a\u064a\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445dd65f7.19665764\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445dd65f7.19665764','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed59.mp3','80','false');show_hide('play','6a04d445dd65f7.19665764');\" \/><input type=\"button\"  id=\"btnstop_6a04d445dd65f7.19665764\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445dd65f7.19665764','','80','false');show_hide('stop','6a04d445dd65f7.19665764');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed59.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\">60<\/td><td class=\"column-2\">\u0645\u0646 \u0627\u0644\u0628\u0627\u0637\u0644 \u0627\u0639\u062a\u0642\u0627\u062f \u0623\u0646\u0651\u064e \u0627\u0644\u062c\u0645\u0627\u0639 \u0641\u064a \u0623\u0648\u0642\u0627\u062a \u0645\u0639\u064a\u0646\u0647 \u064a\u062d\u0635\u0644 \u0645\u0646\u0647 \u0630\u0643\u0631 \u0623\u0648 \u0623\u0646\u062b\u0649<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445de7a83.41567608\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445de7a83.41567608','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed60.mp3','80','false');show_hide('play','6a04d445de7a83.41567608');\" \/><input type=\"button\"  id=\"btnstop_6a04d445de7a83.41567608\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445de7a83.41567608','','80','false');show_hide('stop','6a04d445de7a83.41567608');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed60.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">61<\/td><td class=\"column-2\">\u0647\u0644 \u064a\u0643\u0641\u0631 \u0639\u0648\u0627\u0645 \u0627\u0644\u0631\u0627\u0641\u0636\u0629 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445dff9f1.42091250\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445dff9f1.42091250','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed61.mp3','80','false');show_hide('play','6a04d445dff9f1.42091250');\" \/><input type=\"button\"  id=\"btnstop_6a04d445dff9f1.42091250\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445dff9f1.42091250','','80','false');show_hide('stop','6a04d445dff9f1.42091250');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed61.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">62<\/td><td class=\"column-2\">\u064a\u0646\u0628\u063a\u064a \u062a\u0631\u0643 \u0642\u0648\u0644 \" \u064a\u0627 \u0645\u0648\u0644\u0627\u0646\u0627 \"<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e0d463.64505996\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e0d463.64505996','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed62.mp3','80','false');show_hide('play','6a04d445e0d463.64505996');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e0d463.64505996\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e0d463.64505996','','80','false');show_hide('stop','6a04d445e0d463.64505996');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed62.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">63<\/td><td class=\"column-2\">\u064a\u0643\u0641\u0631 \u0645\u0646 \u0627\u0633\u062a\u062d\u0644 \u0627\u0644\u0645\u0646\u0647\u064a \u0639\u0646\u0647 \u0628\u0627\u0644\u0646\u0635 \u0648\u0627\u0644\u0625\u062c\u0645\u0627\u0639 \u0639\u0644\u0649 \u062a\u062d\u0631\u064a\u0645\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e1a005.10424240\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e1a005.10424240','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed63.mp3','80','false');show_hide('play','6a04d445e1a005.10424240');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e1a005.10424240\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e1a005.10424240','','80','false');show_hide('stop','6a04d445e1a005.10424240');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed63.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">64<\/td><td class=\"column-2\">\u0625\u062b\u0628\u0627\u062a \u0635\u0641\u0627\u062a \u0627\u0644\u0644\u0647 \u062a\u0639\u0627\u0644\u0649 \u0645\u0646 \u063a\u064a\u0631 \u062a\u0634\u0628\u064a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e36618.63096463\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e36618.63096463','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed64.mp3','80','false');show_hide('play','6a04d445e36618.63096463');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e36618.63096463\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e36618.63096463','','80','false');show_hide('stop','6a04d445e36618.63096463');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed64.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">65<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0632\u0639\u0645 \u062c\u0648\u0627\u0632 \u0627\u0644\u0623\u062e\u0630 \u0639\u0646 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639 \u0627\u0633\u062a\u062f\u0644\u0627\u0644\u0627\u064b \u0628\u0642\u0635\u0629 \u0623\u0628\u064a \u0647\u0631\u064a\u0631\u0629 \u0631\u0636\u064a \u0627\u0644\u0644\u0647 \u0639\u0646\u0647 \u0645\u0639 \u0627\u0644\u0634\u064a\u0637\u0627\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e43fb3.22119812\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e43fb3.22119812','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed65.mp3','80','false');show_hide('play','6a04d445e43fb3.22119812');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e43fb3.22119812\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e43fb3.22119812','','80','false');show_hide('stop','6a04d445e43fb3.22119812');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed65.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">66<\/td><td class=\"column-2\">\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0625\u0646\u0634\u0627\u062f \u0627\u0644\u0633\u0644\u0641 \u0644\u0644\u0634\u0639\u0631 \u0648\u0623\u0646\u0627\u0634\u064a\u062f \u0627\u0644\u0635\u0648\u0641\u064a\u0629 \" \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629 \"<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e64c98.12330343\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e64c98.12330343','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed66.mp3','80','false');show_hide('play','6a04d445e64c98.12330343');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e64c98.12330343\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e64c98.12330343','','80','false');show_hide('stop','6a04d445e64c98.12330343');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed66.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">67<\/td><td class=\"column-2\">\u0643\u0641\u0631 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0628\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u062d\u0644\u0648\u0644\u064a\u0629 \u0648\u0627\u0644\u0625\u062a\u062d\u0627\u062f\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e79f99.65454771\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e79f99.65454771','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed67.mp3','80','false');show_hide('play','6a04d445e79f99.65454771');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e79f99.65454771\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e79f99.65454771','','80','false');show_hide('stop','6a04d445e79f99.65454771');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed67.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">68<\/td><td class=\"column-2\">\u0627\u0644\u0634\u064a\u062e \u0631\u0628\u064a\u0639 \u0627\u0644\u0645\u062f\u062e\u0644\u064a \u0644\u0645 \u064a\u0642\u0644 \u0623\u0646\u0651\u064e \u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0645\u0646 \u0627\u0644\u0645\u0643\u0645\u0644\u0627\u062a \u0648\u0623\u0646\u0651\u064e\u0647 \u064a\u062c\u0648\u0632 \u0627\u0644\u062a\u0633\u0627\u0645\u062d \u0639\u0646 \u0627\u0644\u0623\u0635\u0648\u0644<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e881c8.08502009\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e881c8.08502009','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed68.mp3','80','false');show_hide('play','6a04d445e881c8.08502009');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e881c8.08502009\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e881c8.08502009','','80','false');show_hide('stop','6a04d445e881c8.08502009');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed68.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">69<\/td><td class=\"column-2\">\u0627\u0644\u0627\u0633\u062a\u062d\u0644\u0627\u0644 \u0627\u0644\u0642\u0644\u0628\u064a \u0644\u0644\u0645\u0639\u0627\u0635\u064a \u0643\u0641\u0631 \u0628\u0627\u0644\u0644\u0647 \u0628\u062e\u0644\u0627\u0641 \u0627\u0644\u0625\u0633\u062a\u062d\u0644\u0627\u0644 \u0627\u0644\u0641\u0639\u0644\u064a \u0644\u0647\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445e98745.86756664\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445e98745.86756664','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed69.mp3','80','false');show_hide('play','6a04d445e98745.86756664');\" \/><input type=\"button\"  id=\"btnstop_6a04d445e98745.86756664\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445e98745.86756664','','80','false');show_hide('stop','6a04d445e98745.86756664');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed69.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\">70<\/td><td class=\"column-2\">\u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0627\u0644\u0625\u0631\u0647\u0627\u0628\u064a\u0629 \u0645\u0646\u0634\u0623\u0647\u0627 \u0641\u0643\u0631 \u0627\u0644\u062e\u0648\u0627\u0631\u062c \u0648\u0627\u0644\u0630\u064a \u0623\u062d\u064a\u0627\u0647 \u0633\u064a\u062f \u0642\u0637\u0628 \u0648\u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u0648\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ea5e64.40155269\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ea5e64.40155269','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed70.mp3','80','false');show_hide('play','6a04d445ea5e64.40155269');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ea5e64.40155269\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ea5e64.40155269','','80','false');show_hide('stop','6a04d445ea5e64.40155269');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed70.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">71<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u0642\u0627\u0644 \u0627\u0644\u0634\u0631 \u0627\u0644\u0645\u0637\u0644\u0642 \u0648\u0627\u0644\u0646\u0633\u0628\u064a \u0645\u0646 \u0627\u0644\u0644\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445eb37d3.15719642\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445eb37d3.15719642','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed71.mp3','80','false');show_hide('play','6a04d445eb37d3.15719642');\" \/><input type=\"button\"  id=\"btnstop_6a04d445eb37d3.15719642\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445eb37d3.15719642','','80','false');show_hide('stop','6a04d445eb37d3.15719642');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed71.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">72<\/td><td class=\"column-2\">\u0645\u0646 \u0633\u0628 \u0627\u0644\u0644\u0647 \u0623\u0648 \u0627\u0644\u062f\u064a\u0646 \u0623\u0648 \u0627\u0644\u0631\u0633\u0648\u0644 \u064a\u0642\u062f\u0645 \u0644\u0644\u0633\u0644\u0637\u0629 \u0648\u064a\u0642\u062a\u0644 \u0628\u062f\u0648\u0646 \u0627\u0633\u062a\u062a\u0627\u0628\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445ec2900.48535466\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445ec2900.48535466','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed72.mp3','80','false');show_hide('play','6a04d445ec2900.48535466');\" \/><input type=\"button\"  id=\"btnstop_6a04d445ec2900.48535466\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445ec2900.48535466','','80','false');show_hide('stop','6a04d445ec2900.48535466');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed72.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\">73<\/td><td class=\"column-2\">\u0647\u062c\u0631 \u0627\u0644\u062e\u0648\u0627\u0631\u062c \u0644\u0627 \u064a\u0639\u062a\u0628\u0631 \u0645\u0646 \u0642\u0637\u064a\u0639\u0629 \u0627\u0644\u0631\u062d\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445f025b5.08649834\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445f025b5.08649834','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed73.mp3','80','false');show_hide('play','6a04d445f025b5.08649834');\" \/><input type=\"button\"  id=\"btnstop_6a04d445f025b5.08649834\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445f025b5.08649834','','80','false');show_hide('stop','6a04d445f025b5.08649834');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed73.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\">74<\/td><td class=\"column-2\">\u0645\u0627 \u062d\u0643\u0645 \u0625\u0644\u0632\u0627\u0645 \u0627\u0644\u0634\u0628\u0627\u0628 \u0628\u0627\u0644\u0646\u0648\u0627\u0641\u0644 \u0645\u0646 \u0628\u0627\u0628 \u0627\u0644\u062a\u0639\u0627\u0648\u0646 \u0639\u0644\u0649 \u0627\u0644\u0628\u0631 \u0648\u0627\u0644\u062a\u0642\u0648\u0649 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d445f3f247.94225510\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d445f3f247.94225510','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed74.mp3','80','false');show_hide('play','6a04d445f3f247.94225510');\" \/><input type=\"button\"  id=\"btnstop_6a04d445f3f247.94225510\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d445f3f247.94225510','','80','false');show_hide('stop','6a04d445f3f247.94225510');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed74.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td class=\"column-1\">75<\/td><td class=\"column-2\">\u0623\u0633\u0627\u0645\u0629 \u0628\u0646 \u0644\u0627\u062f\u0646 \u0648\u0633\u0639\u062f \u0627\u0644\u0641\u0642\u064a\u0647 \u0647\u0624\u0644\u0627\u0621 \u062e\u0648\u0627\u0631\u062c \u0644\u0627 \u064a\u062c\u0648\u0632 \u0627\u0644\u062b\u0646\u0627\u0621 \u0639\u0644\u064a\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44600dc17.31716775\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44600dc17.31716775','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed75.mp3','80','false');show_hide('play','6a04d44600dc17.31716775');\" \/><input type=\"button\"  id=\"btnstop_6a04d44600dc17.31716775\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44600dc17.31716775','','80','false');show_hide('stop','6a04d44600dc17.31716775');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed75.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\">76<\/td><td class=\"column-2\">\u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u0648\u0646 \u0644\u0647\u0645 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627\u0644\u062a\u0641\u062c\u064a\u0631\u0627\u062a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446037c60.57576955\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446037c60.57576955','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed76.mp3','80','false');show_hide('play','6a04d446037c60.57576955');\" \/><input type=\"button\"  id=\"btnstop_6a04d446037c60.57576955\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446037c60.57576955','','80','false');show_hide('stop','6a04d446037c60.57576955');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed76.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\">77<\/td><td class=\"column-2\">\u0627\u0644\u0633\u0628\u0628 \u0641\u064a \u0648\u062c\u0648\u062f \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0625\u0631\u0647\u0627\u0628\u064a\u0629 \u0627\u0644\u062a\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0641\u0643\u0631 \u0627\u0644\u062e\u0648\u0627\u0631\u062c \u0648\u0628\u0631\u0627\u0621\u0629 \u0643\u062a\u0628 \u0627\u0644\u0625\u0645\u0627\u0645 \u0645\u062d\u0645\u062f \u0628\u0646 \u0639\u0628\u062f \u0627\u0644\u0648\u0647\u0627\u0628 \u0645\u0646 \u0647\u0630\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460467d0.49135625\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460467d0.49135625','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed77.mp3','80','false');show_hide('play','6a04d4460467d0.49135625');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460467d0.49135625\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460467d0.49135625','','80','false');show_hide('stop','6a04d4460467d0.49135625');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed77.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\">78<\/td><td class=\"column-2\">\u0642\u0646\u0627\u0629 \u0627\u0644\u0645\u062c\u062f \u062d\u0632\u0628\u064a\u0629 \u064a\u062c\u0628 \u0627\u0644\u0625\u0628\u062a\u0639\u0627\u062f \u0639\u0646\u0647\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44605bc76.03086865\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44605bc76.03086865','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed78.mp3','80','false');show_hide('play','6a04d44605bc76.03086865');\" \/><input type=\"button\"  id=\"btnstop_6a04d44605bc76.03086865\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44605bc76.03086865','','80','false');show_hide('stop','6a04d44605bc76.03086865');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed78.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">79<\/td><td class=\"column-2\">\u0635\u062d\u0629 \u0648\u0636\u0648\u0621 \u0645\u0646 \u0648\u0642\u0639 \u0641\u064a \u0627\u0644\u0631\u064a\u0627\u0621 \u062b\u0645 \u0627\u0633\u062a\u0639\u0627\u0630 \u0628\u0627\u0644\u0644\u0647 \u0645\u0646\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460692b6.75636877\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460692b6.75636877','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed79.mp3','80','false');show_hide('play','6a04d4460692b6.75636877');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460692b6.75636877\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460692b6.75636877','','80','false');show_hide('stop','6a04d4460692b6.75636877');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed79.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\">80<\/td><td class=\"column-2\">\u0643\u064a\u0641 \u0646\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646\u064e\u0651\u0647 \u0644\u064a\u0633 \u0628\u064a\u0646 \u0623\u0647\u0644 \u0627\u0644\u0633\u0646\u0629 \u0648\u0627\u0644\u0634\u064a\u0639\u0629 \u062e\u0644\u0627\u0641 \u0641\u064a \u0623\u0635\u0648\u0644 \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44608bf36.95131407\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44608bf36.95131407','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed80.mp3','80','false');show_hide('play','6a04d44608bf36.95131407');\" \/><input type=\"button\"  id=\"btnstop_6a04d44608bf36.95131407\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44608bf36.95131407','','80','false');show_hide('stop','6a04d44608bf36.95131407');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed80.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">81<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u062a\u0643\u0641\u064a\u0631 \u0627\u0644\u062d\u0643\u0627\u0645 \u0648\u0648\u0635\u0641 \u0627\u0644\u0633\u0644\u0641\u064a\u064a\u0646 \u0628\u0627\u0644\u0627\u0631\u062c\u0627\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44609a037.40503623\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44609a037.40503623','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed81.mp3','80','false');show_hide('play','6a04d44609a037.40503623');\" \/><input type=\"button\"  id=\"btnstop_6a04d44609a037.40503623\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44609a037.40503623','','80','false');show_hide('stop','6a04d44609a037.40503623');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed81.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">82<\/td><td class=\"column-2\">\u0646\u0635\u064a\u062d\u0629 \u0627\u0644\u0646\u0633\u0627\u0621 \u0645\u0646 \u0641\u0643\u0631 \u0623\u0628\u064a \u0627\u0644\u062d\u0633\u0646 \u0627\u0644\u0645\u0623\u0631\u0628\u064a \u0648\u0623\u062a\u0628\u0627\u0639\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460a7df6.10512551\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460a7df6.10512551','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed82.mp3','80','false');show_hide('play','6a04d4460a7df6.10512551');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460a7df6.10512551\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460a7df6.10512551','','80','false');show_hide('stop','6a04d4460a7df6.10512551');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed82.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\">83<\/td><td class=\"column-2\">\u064a\u062c\u0628 \u0639\u0644\u0649 \u0627\u0644\u0639\u0627\u0645\u064a \u0623\u0646 \u064a\u0642\u0644\u062f \u0645\u0646 \u064a\u062b\u0642 \u0628\u0639\u0644\u0645\u0647 \u0648\u0639\u0642\u064a\u062f\u062a\u0647 \u0641\u0625\u0630\u0627 \u0634\u0643 \u0641\u064a \u0641\u062a\u0648\u0649 \u0633\u0623\u0644 \u0622\u062e\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460b5e68.56183246\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460b5e68.56183246','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed83.mp3','80','false');show_hide('play','6a04d4460b5e68.56183246');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460b5e68.56183246\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460b5e68.56183246','','80','false');show_hide('stop','6a04d4460b5e68.56183246');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed83.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td class=\"column-1\">84<\/td><td class=\"column-2\">\u0623\u0646\u0627 \u0645\u0627 \u0642\u0644\u062a \u0623\u0646\u0651\u064e \u0627\u0644\u062c\u0627\u0646 \u0644\u0648 \u062a\u0643\u0644\u0645 \u0641\u064a \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0645\u0633\u062d\u0648\u0631 \u0641\u0625\u0646\u0647 \u064a\u0635\u062f\u0642<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460c25c7.39119328\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460c25c7.39119328','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed84.mp3','80','false');show_hide('play','6a04d4460c25c7.39119328');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460c25c7.39119328\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460c25c7.39119328','','80','false');show_hide('stop','6a04d4460c25c7.39119328');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed84.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\">85<\/td><td class=\"column-2\">\u0644\u0627 \u0628\u0623\u0633 \u0641\u064a \u0642\u0648\u0644 \u0627\u0644\u0634\u062e\u0635 \u0644\u0644\u0637\u0628\u064a\u0628 \u0623\u0639\u062a\u0645\u062f \u0639\u0644\u0649 \u0627\u0644\u0644\u0647 \u062b\u0645 \u0639\u0644\u064a\u0643 \u0641\u064a \u0646\u062c\u0627\u062d \u0627\u0644\u0639\u0645\u0644\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460d06c3.19671210\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460d06c3.19671210','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed85.mp3','80','false');show_hide('play','6a04d4460d06c3.19671210');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460d06c3.19671210\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460d06c3.19671210','','80','false');show_hide('stop','6a04d4460d06c3.19671210');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed85.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\">86<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u0627\u0644\u0627\u0633\u062a\u0639\u0627\u0646\u0629 \u0628\u0627\u0644\u062c\u0646 \u0644\u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u0633\u062d\u0631 \u0639\u0646 \u0627\u0644\u0645\u0633\u062d\u0648\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460dc8a5.71456507\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460dc8a5.71456507','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed86.mp3','80','false');show_hide('play','6a04d4460dc8a5.71456507');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460dc8a5.71456507\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460dc8a5.71456507','','80','false');show_hide('stop','6a04d4460dc8a5.71456507');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed86.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td class=\"column-1\">87<\/td><td class=\"column-2\">\u064a\u062c\u0648\u0632 \u0627\u0644\u062a\u062d\u062f\u062b \u0645\u0639 \u0625\u062e\u0648\u0627\u0646\u0643 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0635\u0648\u062a \u0644\u0627 \u0627\u0644\u0635\u0648\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460e9660.16436336\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460e9660.16436336','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed87.mp3','80','false');show_hide('play','6a04d4460e9660.16436336');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460e9660.16436336\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460e9660.16436336','','80','false');show_hide('stop','6a04d4460e9660.16436336');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed87.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\">88<\/td><td class=\"column-2\">\u0645\u0627 \u062a\u0648\u062c\u064a\u0647\u0643\u0645 \u0641\u064a\u0645\u0646 \u064a\u0637\u0639\u0646 \u0641\u064a \u0627\u0644\u0634\u064a\u062e \u0631\u0628\u064a\u0639 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4460f7d56.86144997\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4460f7d56.86144997','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed88.mp3','80','false');show_hide('play','6a04d4460f7d56.86144997');\" \/><input type=\"button\"  id=\"btnstop_6a04d4460f7d56.86144997\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4460f7d56.86144997','','80','false');show_hide('stop','6a04d4460f7d56.86144997');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed88.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\">89<\/td><td class=\"column-2\">\u0646\u0635\u064a\u062d\u062a\u0643\u0645 \u0644\u0645\u0646 \u064a\u0641\u062a\u064a \u0627\u0644\u0646\u0627\u0633 \u0628\u063a\u064a\u0631 \u0639\u0644\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446104b38.17036770\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446104b38.17036770','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed89.mp3','80','false');show_hide('play','6a04d446104b38.17036770');\" \/><input type=\"button\"  id=\"btnstop_6a04d446104b38.17036770\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446104b38.17036770','','80','false');show_hide('stop','6a04d446104b38.17036770');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed89.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td class=\"column-1\">90<\/td><td class=\"column-2\">\u0627\u0644\u0647\u062c\u0631 \u064a\u0643\u0648\u0646 \u0628\u0639\u062f \u0627\u0644\u0646\u0635\u064a\u062d\u0629 \u0648\u064a\u062a\u0628\u0639 \u0641\u064a\u0647 \u0627\u0644\u0645\u0635\u0644\u062d\u0629 \u0648\u064a\u0633\u062a\u0641\u062a\u0649 \u0641\u064a\u0647 \u0627\u0644\u0639\u0644\u0645\u0627\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461128c7.27721396\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461128c7.27721396','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed90.mp3','80','false');show_hide('play','6a04d4461128c7.27721396');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461128c7.27721396\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461128c7.27721396','','80','false');show_hide('stop','6a04d4461128c7.27721396');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed90.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\">91<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062d\u0645\u0646 \u0627\u0633\u0645 \u0645\u0646 \u0623\u0633\u0645\u0627\u0621 \u0627\u0644\u0644\u0647 \u062a\u0639\u0627\u0644\u0649 \u0648\u0644\u064a\u0633 \u0644\u0646\u0628\u064a\u0646\u0627 \u0645\u062d\u0645\u062f \u0635\u0644\u0649 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44611fa49.59874976\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44611fa49.59874976','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed91.mp3','80','false');show_hide('play','6a04d44611fa49.59874976');\" \/><input type=\"button\"  id=\"btnstop_6a04d44611fa49.59874976\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44611fa49.59874976','','80','false');show_hide('stop','6a04d44611fa49.59874976');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed91.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-93\">\n\t<td class=\"column-1\">92<\/td><td class=\"column-2\">\u0635\u0627\u0644\u062d \u0627\u0644\u0623\u0633\u0645\u0631\u064a \u0644\u064a\u0633 \u0645\u0646 \u0623\u0647\u0644 \u0627\u0644\u0633\u0646\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446131e20.78194348\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446131e20.78194348','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed92.mp3','80','false');show_hide('play','6a04d446131e20.78194348');\" \/><input type=\"button\"  id=\"btnstop_6a04d446131e20.78194348\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446131e20.78194348','','80','false');show_hide('stop','6a04d446131e20.78194348');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed92.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-94\">\n\t<td class=\"column-1\">93<\/td><td class=\"column-2\">\u0643\u062a\u0627\u0628 \" \u0645\u0643\u0627\u0634\u0641\u0629 \u0627\u0644\u0642\u0644\u0648\u0628 \u0627\u0644\u0645\u0642\u0631\u0628 \u0625\u0644\u0649 \u062d\u0636\u0631\u0629 \u0639\u0644\u0627\u0645 \u0627\u0644\u063a\u064a\u0648\u0628 \"<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461413b6.61998137\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461413b6.61998137','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed93.mp3','80','false');show_hide('play','6a04d4461413b6.61998137');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461413b6.61998137\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461413b6.61998137','','80','false');show_hide('stop','6a04d4461413b6.61998137');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed93.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-95\">\n\t<td class=\"column-1\">94<\/td><td class=\"column-2\">\u0623\u0647\u0645 \u0643\u062a\u0628 \u0627\u0644\u0639\u0642\u064a\u062f\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44614f666.27844251\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44614f666.27844251','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed94.mp3','80','false');show_hide('play','6a04d44614f666.27844251');\" \/><input type=\"button\"  id=\"btnstop_6a04d44614f666.27844251\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44614f666.27844251','','80','false');show_hide('stop','6a04d44614f666.27844251');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed94.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-96\">\n\t<td class=\"column-1\">95<\/td><td class=\"column-2\">\u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u062d\u062c\u0629 \u062a\u0643\u0648\u0646 \u0644\u0644\u0639\u0644\u0645\u0627\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44615c442.38107158\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44615c442.38107158','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed95.mp3','80','false');show_hide('play','6a04d44615c442.38107158');\" \/><input type=\"button\"  id=\"btnstop_6a04d44615c442.38107158\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44615c442.38107158','','80','false');show_hide('stop','6a04d44615c442.38107158');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed95.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-97\">\n\t<td class=\"column-1\">96<\/td><td class=\"column-2\">\u0623\u0628\u0648 \u0625\u0633\u062d\u0627\u0642 \u0627\u0644\u062d\u0648\u064a\u0646\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44616aac2.06712235\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44616aac2.06712235','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed96.mp3','80','false');show_hide('play','6a04d44616aac2.06712235');\" \/><input type=\"button\"  id=\"btnstop_6a04d44616aac2.06712235\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44616aac2.06712235','','80','false');show_hide('stop','6a04d44616aac2.06712235');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed96.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-98\">\n\t<td class=\"column-1\">97<\/td><td class=\"column-2\">\u062a\u0643\u0641\u064a\u0631 \u0627\u0644\u0648\u0644\u0627\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461772c4.23173782\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461772c4.23173782','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed97.mp3','80','false');show_hide('play','6a04d4461772c4.23173782');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461772c4.23173782\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461772c4.23173782','','80','false');show_hide('stop','6a04d4461772c4.23173782');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed97.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-99\">\n\t<td class=\"column-1\">98<\/td><td class=\"column-2\">\u0643\u0627\u0646 \u0627\u0644\u0644\u0647 \u0648\u0644\u0645 \u064a\u0643\u0646 \u0634\u064a\u0621 \u0645\u0639\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446184bf4.58644543\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446184bf4.58644543','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed98.mp3','80','false');show_hide('play','6a04d446184bf4.58644543');\" \/><input type=\"button\"  id=\"btnstop_6a04d446184bf4.58644543\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446184bf4.58644543','','80','false');show_hide('stop','6a04d446184bf4.58644543');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed98.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-100\">\n\t<td class=\"column-1\">99<\/td><td class=\"column-2\">\u0627\u0644\u0625\u0639\u062a\u0642\u0627\u062f \u0641\u064a \u0627\u0644\u0645\u0648\u062a\u0649 \u0634\u0631\u0643 \u0623\u0643\u0628\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446192460.50019744\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446192460.50019744','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed99.mp3','80','false');show_hide('play','6a04d446192460.50019744');\" \/><input type=\"button\"  id=\"btnstop_6a04d446192460.50019744\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446192460.50019744','','80','false');show_hide('stop','6a04d446192460.50019744');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed99.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-101\">\n\t<td class=\"column-1\">100<\/td><td class=\"column-2\">\u0627\u0644\u0647\u062c\u0631\u0629 \u0645\u0646 \u0628\u0644\u0627\u062f \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0625\u0644\u0649 \u0628\u0644\u0627\u062f \u0627\u0644\u0643\u0641\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461a0a18.35280125\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461a0a18.35280125','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed100.mp3','80','false');show_hide('play','6a04d4461a0a18.35280125');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461a0a18.35280125\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461a0a18.35280125','','80','false');show_hide('stop','6a04d4461a0a18.35280125');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed100.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-102\">\n\t<td class=\"column-1\">101<\/td><td class=\"column-2\">\u0627\u0644\u0634\u064a\u062e \u0645\u062d\u0645\u0648\u062f \u0644\u0637\u0641\u064a \u0639\u0627\u0645\u0631 \u0635\u0627\u062d\u0628 \u0633\u0646\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461b2557.91664686\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461b2557.91664686','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed101.mp3','80','false');show_hide('play','6a04d4461b2557.91664686');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461b2557.91664686\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461b2557.91664686','','80','false');show_hide('stop','6a04d4461b2557.91664686');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed101.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-103\">\n\t<td class=\"column-1\">102<\/td><td class=\"column-2\">\u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u062a\u0628\u0644\u064a\u063a \u062e\u0631\u0627\u0641\u064a\u0648\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461be2b9.73325572\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461be2b9.73325572','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed102.mp3','80','false');show_hide('play','6a04d4461be2b9.73325572');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461be2b9.73325572\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461be2b9.73325572','','80','false');show_hide('stop','6a04d4461be2b9.73325572');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed102.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-104\">\n\t<td class=\"column-1\">103<\/td><td class=\"column-2\">\u0642\u0646\u0627\u0629 \u0627\u0644\u0645\u062c\u062f \u064a\u0634\u0631\u0641 \u0639\u0644\u064a\u0647\u0627 \u0627\u0644\u062d\u0632\u0628\u064a\u0648\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461ca8b0.37634599\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461ca8b0.37634599','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed103.mp3','80','false');show_hide('play','6a04d4461ca8b0.37634599');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461ca8b0.37634599\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461ca8b0.37634599','','80','false');show_hide('stop','6a04d4461ca8b0.37634599');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed103.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-105\">\n\t<td class=\"column-1\">104<\/td><td class=\"column-2\">\u0645\u0639\u0646\u0649 \u0642\u0648\u0644 \u0627\u0644\u0628\u0631\u0628\u0647\u0627\u0631\u064a \u0623\u0646\u0651\u064e \u0627\u0644\u0625\u064a\u0645\u0627\u0646 \u064a\u0646\u0642\u0635 \u062d\u062a\u0649 \u0644\u0627 \u064a\u0628\u0642\u0649 \u0645\u0646\u0647 \u0634\u064a\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461d5653.20435621\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461d5653.20435621','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed104.mp3','80','false');show_hide('play','6a04d4461d5653.20435621');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461d5653.20435621\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461d5653.20435621','','80','false');show_hide('stop','6a04d4461d5653.20435621');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed104.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-106\">\n\t<td class=\"column-1\">105<\/td><td class=\"column-2\">\u0646\u0634\u0631 \u0627\u0644\u0623\u0642\u0648\u0627\u0644 \u0628\u0639\u062f \u0639\u0631\u0636\u0647\u0627 \u0639\u0644\u0649 \u0623\u0647\u0644 \u0627\u0644\u0639\u0644\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461e1757.67077421\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461e1757.67077421','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed105.mp3','80','false');show_hide('play','6a04d4461e1757.67077421');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461e1757.67077421\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461e1757.67077421','','80','false');show_hide('stop','6a04d4461e1757.67077421');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed105.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-107\">\n\t<td class=\"column-1\">106<\/td><td class=\"column-2\">\u062a\u0639\u0644\u064a\u0645 \u0627\u0644\u0637\u0641\u0644 \u0623\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646\u0627 \u0633\u0646\u064a \u0633\u0644\u0641\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4461ef662.25478364\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4461ef662.25478364','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed106.mp3','80','false');show_hide('play','6a04d4461ef662.25478364');\" \/><input type=\"button\"  id=\"btnstop_6a04d4461ef662.25478364\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4461ef662.25478364','','80','false');show_hide('stop','6a04d4461ef662.25478364');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed106.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-108\">\n\t<td class=\"column-1\">107<\/td><td class=\"column-2\">\u0627\u0644\u0634\u0631\u0639 \u0645\u0642\u062f\u0645\u064c \u0639\u0644\u0649 \u0627\u0644\u062d\u0643\u0645 \u0628\u0627\u0644\u0639\u0631\u0641<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44620c585.54177755\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44620c585.54177755','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed107.mp3','80','false');show_hide('play','6a04d44620c585.54177755');\" \/><input type=\"button\"  id=\"btnstop_6a04d44620c585.54177755\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44620c585.54177755','','80','false');show_hide('stop','6a04d44620c585.54177755');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed107.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-109\">\n\t<td class=\"column-1\">108<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0627\u0644\u0634\u064a\u0639\u0629 \u0627\u0644\u0630\u064a\u0646 \u064a\u0642\u0648\u0644\u0648\u0646 \u0623\u0646 \u0627\u0644\u0623\u062d\u0627\u062f\u064a\u062b \u0641\u064a \u0641\u0636\u0644 \u0627\u0644\u0635\u062d\u0627\u0628\u0629 \u0643\u0627\u0646\u062a \u0645\u0646 \u0632\u0645\u0646 \u0628\u0646\u064a \u0623\u0645\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44621bd37.14343281\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44621bd37.14343281','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed108.mp3','80','false');show_hide('play','6a04d44621bd37.14343281');\" \/><input type=\"button\"  id=\"btnstop_6a04d44621bd37.14343281\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44621bd37.14343281','','80','false');show_hide('stop','6a04d44621bd37.14343281');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed108.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-110\">\n\t<td class=\"column-1\">109<\/td><td class=\"column-2\">\u0627\u0644\u0635\u0628\u0631 \u0639\u0646 \u0627\u0644\u0647\u062c\u0631\u0629 \u0625\u0644\u0649 \u0628\u0644\u062f \u0627\u0644\u0643\u0641\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44622a6d4.03157892\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44622a6d4.03157892','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed109.mp3','80','false');show_hide('play','6a04d44622a6d4.03157892');\" \/><input type=\"button\"  id=\"btnstop_6a04d44622a6d4.03157892\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44622a6d4.03157892','','80','false');show_hide('stop','6a04d44622a6d4.03157892');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed109.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-111\">\n\t<td class=\"column-1\">110<\/td><td class=\"column-2\">\u062c\u0648\u0627\u0632 \u062a\u0642\u0644\u064a\u062f \u0627\u0644\u0639\u0627\u0645\u064a \u0644\u063a\u064a\u0631\u0647 \u0641\u064a \u0623\u0645\u0648\u0631 \u0627\u0644\u0639\u0642\u064a\u062f\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446238327.02892745\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446238327.02892745','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed110.mp3','80','false');show_hide('play','6a04d446238327.02892745');\" \/><input type=\"button\"  id=\"btnstop_6a04d446238327.02892745\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446238327.02892745','','80','false');show_hide('stop','6a04d446238327.02892745');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed110.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-112\">\n\t<td class=\"column-1\">111<\/td><td class=\"column-2\">\u0643\u064a\u0641 \u0646\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646\u0651\u064e\u0647 \u0644\u064a\u0633 \u0628\u064a\u0646 \u0623\u0647\u0644 \u0627\u0644\u0633\u0646\u0629 \u0648\u0627\u0644\u0634\u064a\u0639\u0629 \u062e\u0644\u0627\u0641 \u0641\u064a \u0623\u0635\u0648\u0644 \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446245892.47807815\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446245892.47807815','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed111.mp3','80','false');show_hide('play','6a04d446245892.47807815');\" \/><input type=\"button\"  id=\"btnstop_6a04d446245892.47807815\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446245892.47807815','','80','false');show_hide('stop','6a04d446245892.47807815');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed111.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-113\">\n\t<td class=\"column-1\">112<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u062a\u0643\u0641\u064a\u0631 \u0627\u0644\u062d\u0643\u0627\u0645 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0648\u0648\u0635\u0641 \u0627\u0644\u0633\u0644\u0641\u064a\u064a\u0646 \u0628\u0627\u0644\u0627\u0631\u062c\u0627\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4462521e9.39422710\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4462521e9.39422710','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed112.mp3','80','false');show_hide('play','6a04d4462521e9.39422710');\" \/><input type=\"button\"  id=\"btnstop_6a04d4462521e9.39422710\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4462521e9.39422710','','80','false');show_hide('stop','6a04d4462521e9.39422710');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed112.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-114\">\n\t<td class=\"column-1\">113<\/td><td class=\"column-2\">\u0645\u0627 \u062d\u0643\u0645 \u0628\u0646\u0627\u0621 \u0627\u0644\u0643\u0646\u0627\u0626\u0633 \u0641\u064a \u0628\u0644\u0627\u062f \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446262535.80468258\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446262535.80468258','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed113.mp3','80','false');show_hide('play','6a04d446262535.80468258');\" \/><input type=\"button\"  id=\"btnstop_6a04d446262535.80468258\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446262535.80468258','','80','false');show_hide('stop','6a04d446262535.80468258');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed113.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-115\">\n\t<td class=\"column-1\">114<\/td><td class=\"column-2\">\u0627\u0644\u062a\u062d\u0627\u0643\u0645 \u0627\u0644\u0649 \u0627\u0644\u0637\u0627\u063a\u0648\u062a \u0644\u0644\u0636\u0631\u0648\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446270304.27009991\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446270304.27009991','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed114.mp3','80','false');show_hide('play','6a04d446270304.27009991');\" \/><input type=\"button\"  id=\"btnstop_6a04d446270304.27009991\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446270304.27009991','','80','false');show_hide('stop','6a04d446270304.27009991');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed114.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-116\">\n\t<td class=\"column-1\">115<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0648\u0628\u0629 \u0625\u0644\u0649 \u0627\u0644\u0644\u0647 \u0645\u0646 \u0623\u062e\u0630 \u0627\u0644\u062c\u0646\u0633\u064a\u0629 \u0627\u0644\u0643\u0627\u0641\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44628a8a8.82624759\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44628a8a8.82624759','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed115.mp3','80','false');show_hide('play','6a04d44628a8a8.82624759');\" \/><input type=\"button\"  id=\"btnstop_6a04d44628a8a8.82624759\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44628a8a8.82624759','','80','false');show_hide('stop','6a04d44628a8a8.82624759');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed115.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-117\">\n\t<td class=\"column-1\">116<\/td><td class=\"column-2\">\u0627\u0644\u0643\u0641\u0627\u0631 \u0641\u064a \u0628\u0644\u0627\u062f \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0623\u0647\u0644 \u0630\u0645\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4462c4da2.63617738\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4462c4da2.63617738','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed116.mp3','80','false');show_hide('play','6a04d4462c4da2.63617738');\" \/><input type=\"button\"  id=\"btnstop_6a04d4462c4da2.63617738\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4462c4da2.63617738','','80','false');show_hide('stop','6a04d4462c4da2.63617738');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed116.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-118\">\n\t<td class=\"column-1\">117<\/td><td class=\"column-2\">\u0643\u062a\u0627\u0628 \u0631\u0641\u0639 \u0627\u0644\u0644\u0627\u0626\u0645\u0629 \u0639\u0646 \u0627\u0644\u0644\u062c\u0646\u0629 \u0627\u0644\u062f\u0627\u0626\u0645\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4462d0fe7.07724277\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4462d0fe7.07724277','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed117.mp3','80','false');show_hide('play','6a04d4462d0fe7.07724277');\" \/><input type=\"button\"  id=\"btnstop_6a04d4462d0fe7.07724277\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4462d0fe7.07724277','','80','false');show_hide('stop','6a04d4462d0fe7.07724277');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed117.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-119\">\n\t<td class=\"column-1\">118<\/td><td class=\"column-2\">\u064a\u062c\u0628 \u0645\u0642\u0627\u0648\u0645\u0629 \u0645\u0630\u0647\u0628 \u0627\u0644\u062a\u0634\u064a\u0639 \u0648\u0645\u0646 \u064a\u0646\u0634\u0631\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4462deb23.68230304\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4462deb23.68230304','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed118.mp3','80','false');show_hide('play','6a04d4462deb23.68230304');\" \/><input type=\"button\"  id=\"btnstop_6a04d4462deb23.68230304\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4462deb23.68230304','','80','false');show_hide('stop','6a04d4462deb23.68230304');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed118.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-120\">\n\t<td class=\"column-1\">119<\/td><td class=\"column-2\">\u0644\u0627 \u0641\u0631\u0642 \u0628\u064a\u0646 \u062a\u0642\u062f\u064a\u0631 \u0627\u0644\u0644\u0647 \u0648\u0645\u0634\u064a\u0626\u062a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446306b28.16700523\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446306b28.16700523','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed119.mp3','80','false');show_hide('play','6a04d446306b28.16700523');\" \/><input type=\"button\"  id=\"btnstop_6a04d446306b28.16700523\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446306b28.16700523','','80','false');show_hide('stop','6a04d446306b28.16700523');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed119.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-121\">\n\t<td class=\"column-1\">120<\/td><td class=\"column-2\">\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0633\u062a\u062d\u0644\u0627\u0644<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446313a53.63745899\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446313a53.63745899','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed120.mp3','80','false');show_hide('play','6a04d446313a53.63745899');\" \/><input type=\"button\"  id=\"btnstop_6a04d446313a53.63745899\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446313a53.63745899','','80','false');show_hide('stop','6a04d446313a53.63745899');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed120.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-122\">\n\t<td class=\"column-1\">121<\/td><td class=\"column-2\">\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u0627\u0633\u062a\u062d\u0644\u0627\u0644 \u0627\u0644\u0641\u0639\u0644\u064a \u0648\u0627\u0644\u0627\u0639\u062a\u0642\u0627\u062f\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44631fd07.55970013\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44631fd07.55970013','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed121.mp3','80','false');show_hide('play','6a04d44631fd07.55970013');\" \/><input type=\"button\"  id=\"btnstop_6a04d44631fd07.55970013\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44631fd07.55970013','','80','false');show_hide('stop','6a04d44631fd07.55970013');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed121.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-123\">\n\t<td class=\"column-1\">122<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646\u0651\u064e \u0627\u0644\u0623\u0644\u0628\u0627\u0646\u064a \u0631\u062d\u0645\u0647 \u0627\u0644\u0644\u0647 \u064a\u0631\u0649 \u062c\u0648\u0627\u0632 \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0627\u0646\u062a\u062d\u0627\u0631\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44632d7c4.73681639\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44632d7c4.73681639','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed122.mp3','80','false');show_hide('play','6a04d44632d7c4.73681639');\" \/><input type=\"button\"  id=\"btnstop_6a04d44632d7c4.73681639\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44632d7c4.73681639','','80','false');show_hide('stop','6a04d44632d7c4.73681639');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed122.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-124\">\n\t<td class=\"column-1\">123<\/td><td class=\"column-2\">\u0625\u0630\u0627 \u0644\u0645 \u064a\u0639\u0631\u0641 \u0627\u0644\u0639\u0627\u0626\u0646 \u064a\u0639\u0627\u0644\u062c \u0627\u0644\u0645\u0635\u0627\u0628 \u0628\u0627\u0644\u0631\u0642\u0649 \u0627\u0644\u0634\u0631\u0639\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446339d76.39282794\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446339d76.39282794','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed123.mp3','80','false');show_hide('play','6a04d446339d76.39282794');\" \/><input type=\"button\"  id=\"btnstop_6a04d446339d76.39282794\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446339d76.39282794','','80','false');show_hide('stop','6a04d446339d76.39282794');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed123.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-125\">\n\t<td class=\"column-1\">124<\/td><td class=\"column-2\">\u0627\u0644\u0645\u064a\u062a \u064a\u0639\u0630\u0628 \u0628\u062f\u064a\u0646\u0647 \u062d\u062a\u0649 \u064a\u0642\u0636\u0649 \u0645\u0627 \u0639\u0644\u064a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446346c72.39510399\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446346c72.39510399','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed124.mp3','80','false');show_hide('play','6a04d446346c72.39510399');\" \/><input type=\"button\"  id=\"btnstop_6a04d446346c72.39510399\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446346c72.39510399','','80','false');show_hide('stop','6a04d446346c72.39510399');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed124.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-126\">\n\t<td class=\"column-1\">125<\/td><td class=\"column-2\">\u0627\u0644\u0647\u062c\u0631\u0629 \u0645\u0646 \u0628\u0644\u062f \u0643\u0641\u0631 \u0625\u0644\u0649 \u0628\u0644\u062f \u0645\u062b\u0644\u0647 \u0647\u0630\u0627 \u0644\u0627 \u064a\u0639\u062a\u0628\u0631 \u0647\u062c\u0631\u0629 \u0634\u0631\u0639\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446354828.73061397\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446354828.73061397','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed125.mp3','80','false');show_hide('play','6a04d446354828.73061397');\" \/><input type=\"button\"  id=\"btnstop_6a04d446354828.73061397\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446354828.73061397','','80','false');show_hide('stop','6a04d446354828.73061397');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed125.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-127\">\n\t<td class=\"column-1\">126<\/td><td class=\"column-2\">\u0635\u0648\u0631 \u0630\u0648\u0627\u062a \u0627\u0644\u0623\u0631\u0648\u0627\u062d \u0644\u0627 \u062a\u062c\u0648\u0632<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446361042.13329930\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446361042.13329930','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed126.mp3','80','false');show_hide('play','6a04d446361042.13329930');\" \/><input type=\"button\"  id=\"btnstop_6a04d446361042.13329930\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446361042.13329930','','80','false');show_hide('stop','6a04d446361042.13329930');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed126.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-128\">\n\t<td class=\"column-1\">127<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0623\u0647\u0644 \u0627\u0644\u0623\u0630\u0643\u0627\u0631 \u0627\u0644\u062c\u0645\u0627\u0639\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44636f794.65004343\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44636f794.65004343','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed127.mp3','80','false');show_hide('play','6a04d44636f794.65004343');\" \/><input type=\"button\"  id=\"btnstop_6a04d44636f794.65004343\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44636f794.65004343','','80','false');show_hide('stop','6a04d44636f794.65004343');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed127.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-129\">\n\t<td class=\"column-1\">128<\/td><td class=\"column-2\">\u062a\u0631\u0643 \u0627\u0644\u0635\u0644\u0627\u0629 \u062e\u0644\u0641 \u0627\u0644\u0625\u0628\u0627\u0636\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44637c8e5.58753391\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44637c8e5.58753391','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed128.mp3','80','false');show_hide('play','6a04d44637c8e5.58753391');\" \/><input type=\"button\"  id=\"btnstop_6a04d44637c8e5.58753391\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44637c8e5.58753391','','80','false');show_hide('stop','6a04d44637c8e5.58753391');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed128.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-130\">\n\t<td class=\"column-1\">129<\/td><td class=\"column-2\">\u062c\u0648\u0627\u0632 \u062f\u062e\u0648\u0644 \u0627\u0644\u0646\u0635\u0627\u0631\u0649 \u0648\u0627\u0644\u064a\u0647\u0648\u062f \u0641\u064a \u0627\u0644\u0645\u0633\u0627\u062c\u062f \u0625\u0644\u0627\u064e\u0651 \u0641\u064a \u0627\u0644\u0645\u0633\u062c\u062f \u0627\u0644\u062d\u0631\u0627\u0645 \u060c \u0648\u0644\u0627 \u064a\u0646\u0628\u063a\u064a \u0630\u0647\u0627\u0628 \u0627\u0644\u0645\u0633\u0644\u0645 \u0625\u0644\u0649 \u0627\u0644\u0643\u0646\u0627\u0626\u0633 \u0648\u0627\u0644\u0645\u0639\u0627\u0628\u062f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446387a63.59712483\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446387a63.59712483','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed129.mp3','80','false');show_hide('play','6a04d446387a63.59712483');\" \/><input type=\"button\"  id=\"btnstop_6a04d446387a63.59712483\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446387a63.59712483','','80','false');show_hide('stop','6a04d446387a63.59712483');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed129.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-131\">\n\t<td class=\"column-1\">130<\/td><td class=\"column-2\">\u0639\u062f\u0645 \u062c\u0648\u0627\u0632 \u0627\u0644\u062a\u062d\u062f\u062b \u0645\u0639 \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0628\u0627\u0644\u0635\u0648\u062a \u0648\u0627\u0644\u0635\u0648\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4463931b2.97929846\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4463931b2.97929846','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed130.mp3','80','false');show_hide('play','6a04d4463931b2.97929846');\" \/><input type=\"button\"  id=\"btnstop_6a04d4463931b2.97929846\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4463931b2.97929846','','80','false');show_hide('stop','6a04d4463931b2.97929846');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed130.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-132\">\n\t<td class=\"column-1\">131<\/td><td class=\"column-2\">\u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u062d\u062c\u0629 \u062a\u0643\u0648\u0646 \u0641\u064a \u0627\u0644\u062a\u0643\u0641\u064a\u0631 \u0641\u0642\u0637<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44639f089.10394827\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44639f089.10394827','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed131.mp3','80','false');show_hide('play','6a04d44639f089.10394827');\" \/><input type=\"button\"  id=\"btnstop_6a04d44639f089.10394827\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44639f089.10394827','','80','false');show_hide('stop','6a04d44639f089.10394827');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed131.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-133\">\n\t<td class=\"column-1\">132<\/td><td class=\"column-2\">\u0623\u0647\u0644 \u0627\u0644\u0633\u0646\u0629 \u0644\u0627 \u064a\u0646\u062a\u0633\u0628\u0648\u0646 \u0644\u0644\u0623\u0634\u062e\u0627\u0635 \u0628\u0644 \u0644\u0644\u0633\u0646\u0629 \u0648\u0627\u0644\u0633\u0644\u0641\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4463b3003.43141446\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4463b3003.43141446','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed132.mp3','80','false');show_hide('play','6a04d4463b3003.43141446');\" \/><input type=\"button\"  id=\"btnstop_6a04d4463b3003.43141446\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4463b3003.43141446','','80','false');show_hide('stop','6a04d4463b3003.43141446');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed132.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-134\">\n\t<td class=\"column-1\">133<\/td><td class=\"column-2\">\u0627\u0644\u062d\u0632\u0628\u064a \u0647\u0648 \u0627\u0644\u0630\u064a \u064a\u0646\u0635\u062d \u0628\u0643\u062a\u0628 \u0623\u0628\u0648 \u0627\u0644\u0623\u0639\u0644\u0649 \u0627\u0644\u0645\u0648\u062f\u0648\u062f\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4463c3467.97380927\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4463c3467.97380927','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed133.mp3','80','false');show_hide('play','6a04d4463c3467.97380927');\" \/><input type=\"button\"  id=\"btnstop_6a04d4463c3467.97380927\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4463c3467.97380927','','80','false');show_hide('stop','6a04d4463c3467.97380927');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed133.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-135\">\n\t<td class=\"column-1\">134<\/td><td class=\"column-2\">\u0644\u0627 \u0623\u0631\u0649 \u0627\u0644\u062a\u0635\u0648\u064a\u062a \u0644\u0644\u0643\u0627\u0641\u0631 \u0648\u0644\u0648 \u0643\u0627\u0646 \u0641\u064a\u0647 \u0645\u0635\u0644\u062d\u0629 \u0644\u0644\u0645\u0633\u0644\u0645\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4463d2932.71768493\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4463d2932.71768493','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed134.mp3','80','false');show_hide('play','6a04d4463d2932.71768493');\" \/><input type=\"button\"  id=\"btnstop_6a04d4463d2932.71768493\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4463d2932.71768493','','80','false');show_hide('stop','6a04d4463d2932.71768493');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed134.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-136\">\n\t<td class=\"column-1\">135<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u0627\u0644\u062a\u0635\u0648\u064a\u062a \u0644\u0635\u0627\u0644\u062d \u0627\u0644\u0643\u0641\u0627\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4463e26f4.98915842\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4463e26f4.98915842','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed135.mp3','80','false');show_hide('play','6a04d4463e26f4.98915842');\" \/><input type=\"button\"  id=\"btnstop_6a04d4463e26f4.98915842\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4463e26f4.98915842','','80','false');show_hide('stop','6a04d4463e26f4.98915842');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed135.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-137\">\n\t<td class=\"column-1\">136<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u0646\u0628\u063a\u064a \u062e\u0644\u0637 \u0627\u0644\u062f\u0631\u0648\u0633 \u0627\u0644\u0633\u0644\u0641\u064a\u0629 \u0628\u063a\u064a\u0631\u0647\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4463f0426.85159339\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4463f0426.85159339','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed136.mp3','80','false');show_hide('play','6a04d4463f0426.85159339');\" \/><input type=\"button\"  id=\"btnstop_6a04d4463f0426.85159339\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4463f0426.85159339','','80','false');show_hide('stop','6a04d4463f0426.85159339');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed136.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-138\">\n\t<td class=\"column-1\">137<\/td><td class=\"column-2\">\u062a\u062c\u0628 \u0645\u0646\u0627\u0635\u062d\u0629 \u0627\u0644\u0633\u0644\u0637\u0627\u0646 \u0625\u0630\u0627 \u062e\u0627\u0644\u0641 \u0623\u0645\u0648\u0631 \u0634\u0631\u0639\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446400873.91146688\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446400873.91146688','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed137.mp3','80','false');show_hide('play','6a04d446400873.91146688');\" \/><input type=\"button\"  id=\"btnstop_6a04d446400873.91146688\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446400873.91146688','','80','false');show_hide('stop','6a04d446400873.91146688');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed137.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-139\">\n\t<td class=\"column-1\">138<\/td><td class=\"column-2\">\u0639\u0644\u0645 \u0627\u0644\u0643\u0644\u0627\u0645 \u0630\u0645\u0647 \u0627\u0644\u062f\u0627\u0631\u0642\u0637\u0646\u064a \u0648\u063a\u064a\u0631\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44640e9b8.35721815\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44640e9b8.35721815','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed138.mp3','80','false');show_hide('play','6a04d44640e9b8.35721815');\" \/><input type=\"button\"  id=\"btnstop_6a04d44640e9b8.35721815\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44640e9b8.35721815','','80','false');show_hide('stop','6a04d44640e9b8.35721815');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed138.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-140\">\n\t<td class=\"column-1\">139<\/td><td class=\"column-2\">\u0644\u0627 \u062a\u062c\u0648\u0632 \u0627\u0644\u0635\u0644\u0627\u0629 \u0641\u064a \u0645\u0633\u062c\u062f \u0627\u0644\u0642\u0628\u0648\u0631 \u0641\u064a \u0642\u0628\u0644\u062a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44641b464.31480299\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44641b464.31480299','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed139.mp3','80','false');show_hide('play','6a04d44641b464.31480299');\" \/><input type=\"button\"  id=\"btnstop_6a04d44641b464.31480299\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44641b464.31480299','','80','false');show_hide('stop','6a04d44641b464.31480299');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed139.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-141\">\n\t<td class=\"column-1\">140<\/td><td class=\"column-2\">\u0627\u0644\u0643\u062a\u0628 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0644\u0645\u0628\u062a\u062f\u0626 \u0641\u064a \u0628\u0627\u0628 \u0627\u0644\u0623\u0633\u0645\u0627\u0621 \u0648\u0627\u0644\u0635\u0641\u0627\u062a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446427eb6.61913663\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446427eb6.61913663','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed140.mp3','80','false');show_hide('play','6a04d446427eb6.61913663');\" \/><input type=\"button\"  id=\"btnstop_6a04d446427eb6.61913663\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446427eb6.61913663','','80','false');show_hide('stop','6a04d446427eb6.61913663');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed140.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-142\">\n\t<td class=\"column-1\">141<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062f\u0631\u0633 \u0639\u0644\u0649 \u064a\u062f \u062f\u0627\u0639\u064a\u0629 \u064a\u062c\u0627\u0644\u0633 \u0627\u0644\u062d\u0632\u0628\u064a\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446434c91.61455530\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446434c91.61455530','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed141.mp3','80','false');show_hide('play','6a04d446434c91.61455530');\" \/><input type=\"button\"  id=\"btnstop_6a04d446434c91.61455530\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446434c91.61455530','','80','false');show_hide('stop','6a04d446434c91.61455530');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed141.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-143\">\n\t<td class=\"column-1\">142<\/td><td class=\"column-2\">\u0627\u0644\u0639\u0644\u0645\u0627\u0646\u064a \u0623\u062e\u0637\u0631 \u0645\u0646 \u0627\u0644\u0645\u0628\u062a\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4464413b1.21725955\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4464413b1.21725955','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed142.mp3','80','false');show_hide('play','6a04d4464413b1.21725955');\" \/><input type=\"button\"  id=\"btnstop_6a04d4464413b1.21725955\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4464413b1.21725955','','80','false');show_hide('stop','6a04d4464413b1.21725955');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed142.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-144\">\n\t<td class=\"column-1\">143<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0628\u0644\u064a\u063a\u064a\u064a\u0646 \u062e\u0631\u0627\u0641\u064a\u0648\u0646 \u0648\u0639\u0646\u062f\u0647\u0645 \u0639\u0642\u0627\u0626\u062f \u0633\u064a\u0626\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44644de05.32237016\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44644de05.32237016','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed143.mp3','80','false');show_hide('play','6a04d44644de05.32237016');\" \/><input type=\"button\"  id=\"btnstop_6a04d44644de05.32237016\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44644de05.32237016','','80','false');show_hide('stop','6a04d44644de05.32237016');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed143.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-145\">\n\t<td class=\"column-1\">144<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0639\u0644\u064a\u0645 \u0644\u0627 \u064a\u062d\u062a\u0627\u062c \u0641\u064a\u0647 \u0625\u0644\u0649 \u0627\u0644\u0635\u0648\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44645a478.10667315\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44645a478.10667315','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed144.mp3','80','false');show_hide('play','6a04d44645a478.10667315');\" \/><input type=\"button\"  id=\"btnstop_6a04d44645a478.10667315\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44645a478.10667315','','80','false');show_hide('stop','6a04d44645a478.10667315');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed144.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-146\">\n\t<td class=\"column-1\">145<\/td><td class=\"column-2\">\u0635\u0627\u0644\u062d \u0627\u0644\u0623\u0633\u0645\u0631\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446468db6.27672862\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446468db6.27672862','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed145.mp3','80','false');show_hide('play','6a04d446468db6.27672862');\" \/><input type=\"button\"  id=\"btnstop_6a04d446468db6.27672862\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446468db6.27672862','','80','false');show_hide('stop','6a04d446468db6.27672862');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed145.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-147\">\n\t<td class=\"column-1\">146<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u0623\u0646 \u064a\u0631\u062b \u0627\u0644\u0645\u0633\u0644\u0645 \u0627\u0644\u0643\u0627\u0641\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446474f90.88167411\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446474f90.88167411','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed146.mp3','80','false');show_hide('play','6a04d446474f90.88167411');\" \/><input type=\"button\"  id=\"btnstop_6a04d446474f90.88167411\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446474f90.88167411','','80','false');show_hide('stop','6a04d446474f90.88167411');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed146.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-148\">\n\t<td class=\"column-1\">147<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u0646\u0628\u063a\u064a \u0642\u0648\u0644 \u0627\u0644\u0642\u0627\u0626\u0644 \u0644\u064a\u0633 \u0644\u062f\u064a \u062d\u0638<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4464812e7.92792795\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4464812e7.92792795','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed147.mp3','80','false');show_hide('play','6a04d4464812e7.92792795');\" \/><input type=\"button\"  id=\"btnstop_6a04d4464812e7.92792795\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4464812e7.92792795','','80','false');show_hide('stop','6a04d4464812e7.92792795');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed147.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-149\">\n\t<td class=\"column-1\">148<\/td><td class=\"column-2\">\u0627\u0644\u0645\u0646\u0634\u062f \u0631\u0627\u0634\u062f \u0627\u0644\u0639\u0641\u0627\u0633\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44648e3e0.47902140\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44648e3e0.47902140','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed148.mp3','80','false');show_hide('play','6a04d44648e3e0.47902140');\" \/><input type=\"button\"  id=\"btnstop_6a04d44648e3e0.47902140\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44648e3e0.47902140','','80','false');show_hide('stop','6a04d44648e3e0.47902140');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed148.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-150\">\n\t<td class=\"column-1\">149<\/td><td class=\"column-2\">\u0627\u0644\u0646\u0633\u0627\u0621 \u0645\u0646 \u0627\u0644\u0645\u0633\u062a\u0636\u0639\u0641\u064a\u0646 \u0627\u0644\u0630\u064a\u0646 \u0639\u0630\u0631\u0647\u0645 \u0627\u0644\u0644\u0647 \u0641\u064a \u062a\u0631\u0643 \u0627\u0644\u0647\u062c\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44649d034.40146060\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44649d034.40146060','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed149.mp3','80','false');show_hide('play','6a04d44649d034.40146060');\" \/><input type=\"button\"  id=\"btnstop_6a04d44649d034.40146060\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44649d034.40146060','','80','false');show_hide('stop','6a04d44649d034.40146060');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed149.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-151\">\n\t<td class=\"column-1\">150<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062a\u0631\u062f\u062f \u0641\u064a \u062a\u0643\u0641\u064a\u0631 \u0627\u0644\u0643\u0641\u0627\u0631 \u0627\u0644\u0623\u0635\u0644\u064a\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4464aa708.63961979\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4464aa708.63961979','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed150.mp3','80','false');show_hide('play','6a04d4464aa708.63961979');\" \/><input type=\"button\"  id=\"btnstop_6a04d4464aa708.63961979\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4464aa708.63961979','','80','false');show_hide('stop','6a04d4464aa708.63961979');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed150.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-152\">\n\t<td class=\"column-1\">151<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u0627\u0644\u0627\u0633\u062a\u0645\u0627\u0639 \u0644\u0644\u0623\u0646\u0627\u0634\u064a\u062f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4464bd4c4.94400097\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4464bd4c4.94400097','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed151.mp3','80','false');show_hide('play','6a04d4464bd4c4.94400097');\" \/><input type=\"button\"  id=\"btnstop_6a04d4464bd4c4.94400097\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4464bd4c4.94400097','','80','false');show_hide('stop','6a04d4464bd4c4.94400097');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed151.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-153\">\n\t<td class=\"column-1\">152<\/td><td class=\"column-2\">\u0645\u0635\u064a\u0631 \u0627\u0644\u0623\u0631\u0648\u0627\u062d \u0628\u0639\u062f \u0641\u0631\u0627\u0642\u0647\u0627 \u0645\u0646 \u0627\u0644\u0623\u062c\u0633\u0627\u062f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4464cbd22.66102900\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4464cbd22.66102900','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed152.mp3','80','false');show_hide('play','6a04d4464cbd22.66102900');\" \/><input type=\"button\"  id=\"btnstop_6a04d4464cbd22.66102900\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4464cbd22.66102900','','80','false');show_hide('stop','6a04d4464cbd22.66102900');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed152.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-154\">\n\t<td class=\"column-1\">153<\/td><td class=\"column-2\">\u0623\u0642\u0648\u0627\u0644 \u0648\u0623\u0641\u0639\u0627\u0644 \u0627\u0644\u0631\u064f\u0651\u0633\u0644 \u062d\u064f\u062c\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4464d8854.46816394\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4464d8854.46816394','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed153.mp3','80','false');show_hide('play','6a04d4464d8854.46816394');\" \/><input type=\"button\"  id=\"btnstop_6a04d4464d8854.46816394\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4464d8854.46816394','','80','false');show_hide('stop','6a04d4464d8854.46816394');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed153.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-155\">\n\t<td class=\"column-1\">154<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646 \u0627\u0644\u062d\u062c\u0627\u0628 \u0644\u064a\u0633 \u0628\u0648\u0627\u062c\u0628 \u0639\u0644\u0649 \u0627\u0644\u0645\u0631\u0623\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4464e5311.29016754\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4464e5311.29016754','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed154.mp3','80','false');show_hide('play','6a04d4464e5311.29016754');\" \/><input type=\"button\"  id=\"btnstop_6a04d4464e5311.29016754\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4464e5311.29016754','','80','false');show_hide('stop','6a04d4464e5311.29016754');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed154.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-156\">\n\t<td class=\"column-1\">155<\/td><td class=\"column-2\">\u0627\u0644\u062f\u0643\u062a\u0648\u0631 \u0627\u0644\u0633\u064a\u062f \u0627\u0644\u0639\u0641\u0627\u0646\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44650b591.08124738\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44650b591.08124738','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed155.mp3','80','false');show_hide('play','6a04d44650b591.08124738');\" \/><input type=\"button\"  id=\"btnstop_6a04d44650b591.08124738\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44650b591.08124738','','80','false');show_hide('stop','6a04d44650b591.08124738');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed155.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-157\">\n\t<td class=\"column-1\">156<\/td><td class=\"column-2\">\u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0641\u064a \u0627\u0644\u0627\u0646\u062a\u062e\u0627\u0628\u0627\u062a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446519b16.57507837\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446519b16.57507837','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed156.mp3','80','false');show_hide('play','6a04d446519b16.57507837');\" \/><input type=\"button\"  id=\"btnstop_6a04d446519b16.57507837\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446519b16.57507837','','80','false');show_hide('stop','6a04d446519b16.57507837');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed156.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-158\">\n\t<td class=\"column-1\">157<\/td><td class=\"column-2\">\u0627\u0644\u0645\u0633\u062d\u0648\u0631 \u0647\u0648 \u0627\u0644\u0630\u064a \u064a\u062a\u0623\u062b\u0631 \u0628\u0622\u064a\u0627\u062a \u0627\u0644\u0633\u062d\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465441d6.43452034\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465441d6.43452034','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed157.mp3','80','false');show_hide('play','6a04d4465441d6.43452034');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465441d6.43452034\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465441d6.43452034','','80','false');show_hide('stop','6a04d4465441d6.43452034');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed157.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-159\">\n\t<td class=\"column-1\">158<\/td><td class=\"column-2\">\u0627\u0644\u0646\u062c\u0627\u0634\u064a \u0645\u0627\u062a \u0639\u0644\u0649 \u0627\u0644\u0625\u0633\u0644\u0627\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446557142.19949696\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446557142.19949696','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed158.mp3','80','false');show_hide('play','6a04d446557142.19949696');\" \/><input type=\"button\"  id=\"btnstop_6a04d446557142.19949696\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446557142.19949696','','80','false');show_hide('stop','6a04d446557142.19949696');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed158.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-160\">\n\t<td class=\"column-1\">159<\/td><td class=\"column-2\">\u062c\u0648\u0627\u0632 \u0631\u0642\u064a\u0629 \u0627\u0644\u0645\u0633\u0644\u0645 \u0644\u0644\u0643\u0627\u0641\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446566c15.79395935\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446566c15.79395935','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed159.mp3','80','false');show_hide('play','6a04d446566c15.79395935');\" \/><input type=\"button\"  id=\"btnstop_6a04d446566c15.79395935\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446566c15.79395935','','80','false');show_hide('stop','6a04d446566c15.79395935');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed159.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-161\">\n\t<td class=\"column-1\">160<\/td><td class=\"column-2\">\u0637\u0627\u0639\u0629 \u0627\u0644\u0623\u0645 \u0641\u064a \u062a\u0631\u0643 \u0627\u0644\u0647\u062c\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465755a8.75498995\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465755a8.75498995','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed160.mp3','80','false');show_hide('play','6a04d4465755a8.75498995');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465755a8.75498995\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465755a8.75498995','','80','false');show_hide('stop','6a04d4465755a8.75498995');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed160.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-162\">\n\t<td class=\"column-1\">161<\/td><td class=\"column-2\">\u0639\u0628\u062f \u0627\u0644\u0631\u062d\u0645\u0646 \u0627\u0644\u0645\u063a\u0631\u0648\u0627\u064a \u0631\u062c\u0644\u064c \u062a\u0643\u0641\u064a\u0631\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446585707.70280518\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446585707.70280518','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed161.mp3','80','false');show_hide('play','6a04d446585707.70280518');\" \/><input type=\"button\"  id=\"btnstop_6a04d446585707.70280518\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446585707.70280518','','80','false');show_hide('stop','6a04d446585707.70280518');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed161.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-163\">\n\t<td class=\"column-1\">162<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u0627\u0644\u062d\u0644\u0641 \u0628\u0627\u0644\u0639\u0645\u0631 \u0644\u0623\u0646\u0651\u064e\u0647 \u0634\u0631\u0643<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446593555.65577007\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446593555.65577007','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed162.mp3','80','false');show_hide('play','6a04d446593555.65577007');\" \/><input type=\"button\"  id=\"btnstop_6a04d446593555.65577007\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446593555.65577007','','80','false');show_hide('stop','6a04d446593555.65577007');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed162.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-164\">\n\t<td class=\"column-1\">163<\/td><td class=\"column-2\">\u064a\u062c\u0648\u0632 \u0625\u062e\u0628\u0627\u0631 \u0627\u0644\u0633\u0644\u0641\u064a \u0628\u0627\u0644\u062a\u0643\u0641\u064a\u0631\u064a \u0641\u064a \u0628\u0644\u0627\u062f \u0627\u0644\u0643\u0641\u0627\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465a2911.31139653\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465a2911.31139653','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed163.mp3','80','false');show_hide('play','6a04d4465a2911.31139653');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465a2911.31139653\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465a2911.31139653','','80','false');show_hide('stop','6a04d4465a2911.31139653');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed163.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-165\">\n\t<td class=\"column-1\">164<\/td><td class=\"column-2\">\u0644\u0627 \u064a\u062c\u0648\u0632 \u062a\u0631\u062c\u0645\u0629 \u0643\u062a\u0628 \u0627\u0644\u062d\u0632\u0628\u064a\u064a\u0646 \u0623\u0648 \u0645\u0646 \u0648\u0627\u0641\u0642\u0647\u0645 \u0639\u0644\u0649 \u0628\u0627\u0637\u0644\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465b1512.09442423\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465b1512.09442423','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed164.mp3','80','false');show_hide('play','6a04d4465b1512.09442423');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465b1512.09442423\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465b1512.09442423','','80','false');show_hide('stop','6a04d4465b1512.09442423');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed164.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-166\">\n\t<td class=\"column-1\">165<\/td><td class=\"column-2\">\u0627\u0644\u062e\u0648\u0627\u0631\u062c \u0644\u0647\u0645 \u0639\u0642\u0627\u0626\u062f \u0641\u0627\u0633\u062f\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465c0185.11703991\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465c0185.11703991','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed165.mp3','80','false');show_hide('play','6a04d4465c0185.11703991');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465c0185.11703991\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465c0185.11703991','','80','false');show_hide('stop','6a04d4465c0185.11703991');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed165.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-167\">\n\t<td class=\"column-1\">166<\/td><td class=\"column-2\">\u0627\u0644\u0633\u0641\u0631 \u0644\u0628\u0644\u0627\u062f \u0627\u0644\u0643\u0641\u0631 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062f\u0631\u0627\u0633\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465d3d57.27498441\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465d3d57.27498441','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed166.mp3','80','false');show_hide('play','6a04d4465d3d57.27498441');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465d3d57.27498441\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465d3d57.27498441','','80','false');show_hide('stop','6a04d4465d3d57.27498441');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed166.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-168\">\n\t<td class=\"column-1\">167<\/td><td class=\"column-2\">\u0645\u0627 \u0645\u0639\u0646\u0649 \u0627\u0644\u0633\u0644\u0641\u064a\u0629 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465e2254.57504682\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465e2254.57504682','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed167.mp3','80','false');show_hide('play','6a04d4465e2254.57504682');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465e2254.57504682\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465e2254.57504682','','80','false');show_hide('stop','6a04d4465e2254.57504682');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed167.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-169\">\n\t<td class=\"column-1\">168<\/td><td class=\"column-2\">\u062c\u0648\u0627\u0632 \u0630\u0643\u0631 \u0627\u0633\u0645 \u0627\u0644\u0645\u0628\u062a\u062f\u0639 \u0644\u0644\u062a\u062d\u0630\u064a\u0631 \u0645\u0646\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465f0f37.48930058\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465f0f37.48930058','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed168.mp3','80','false');show_hide('play','6a04d4465f0f37.48930058');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465f0f37.48930058\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465f0f37.48930058','','80','false');show_hide('stop','6a04d4465f0f37.48930058');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed168.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-170\">\n\t<td class=\"column-1\">169<\/td><td class=\"column-2\">\u0645\u0627 \u0647\u064a \u0627\u0644\u062c\u0627\u0645\u064a\u0629 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4465fe631.93091724\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4465fe631.93091724','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed169.mp3','80','false');show_hide('play','6a04d4465fe631.93091724');\" \/><input type=\"button\"  id=\"btnstop_6a04d4465fe631.93091724\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4465fe631.93091724','','80','false');show_hide('stop','6a04d4465fe631.93091724');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed169.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-171\">\n\t<td class=\"column-1\">170<\/td><td class=\"column-2\">\u0627\u0644\u0623\u0646\u0627\u0634\u064a\u062f \u0635\u0648\u0641\u064a\u0629 \u0648\u0644\u064a\u0633\u062a \u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44660c5b4.64128289\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44660c5b4.64128289','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed170.mp3','80','false');show_hide('play','6a04d44660c5b4.64128289');\" \/><input type=\"button\"  id=\"btnstop_6a04d44660c5b4.64128289\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44660c5b4.64128289','','80','false');show_hide('stop','6a04d44660c5b4.64128289');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed170.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-172\">\n\t<td class=\"column-1\">171<\/td><td class=\"column-2\">\u0644\u0641\u0638\u0629 ( \u0627\u0644\u0644\u0647 \u0623\u0628\u0648\u0643 ) \u062d\u0631\u0627\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44661a0b9.89294130\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44661a0b9.89294130','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed171.mp3','80','false');show_hide('play','6a04d44661a0b9.89294130');\" \/><input type=\"button\"  id=\"btnstop_6a04d44661a0b9.89294130\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44661a0b9.89294130','','80','false');show_hide('stop','6a04d44661a0b9.89294130');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed171.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-173\">\n\t<td class=\"column-1\">172<\/td><td class=\"column-2\">\u0645\u062a\u0649 \u064a\u0639\u0630\u0631 \u0627\u0644\u0645\u0633\u0644\u0645 \u0645\u0646 \u0627\u0644\u0647\u062c\u0631\u0629 \u0645\u0646 \u0628\u0644\u0627\u062f \u0627\u0644\u0643\u0641\u0631 \u0625\u0644\u0649 \u0628\u0644\u0627\u062f \u0627\u0644\u0627\u0633\u0644\u0627\u0645 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446629014.84598104\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446629014.84598104','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed172.mp3','80','false');show_hide('play','6a04d446629014.84598104');\" \/><input type=\"button\"  id=\"btnstop_6a04d446629014.84598104\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446629014.84598104','','80','false');show_hide('stop','6a04d446629014.84598104');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed172.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-174\">\n\t<td class=\"column-1\">173<\/td><td class=\"column-2\">\u064a\u0635\u0644\u0649 \u062e\u0644\u0641 \u0627\u0644\u0625\u0645\u0627\u0645 \u0627\u0644\u0630\u064a \u064a\u062e\u0634\u0649 \u0645\u0646 \u0623\u0630\u064a\u062a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446637266.02018113\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446637266.02018113','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed173.mp3','80','false');show_hide('play','6a04d446637266.02018113');\" \/><input type=\"button\"  id=\"btnstop_6a04d446637266.02018113\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446637266.02018113','','80','false');show_hide('stop','6a04d446637266.02018113');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed173.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-175\">\n\t<td class=\"column-1\">174<\/td><td class=\"column-2\">\u0627\u0644\u062d\u0643\u0645 \u0628\u0627\u0644\u0628\u062f\u0639\u0629 \u0648\u0627\u0644\u062a\u0628\u062f\u064a\u0639 \u064a\u0643\u0648\u0646 \u0644\u0623\u0647\u0644 \u0627\u0644\u0639\u0644\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446645b76.07216246\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446645b76.07216246','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed174.mp3','80','false');show_hide('play','6a04d446645b76.07216246');\" \/><input type=\"button\"  id=\"btnstop_6a04d446645b76.07216246\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446645b76.07216246','','80','false');show_hide('stop','6a04d446645b76.07216246');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed174.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-176\">\n\t<td class=\"column-1\">175<\/td><td class=\"column-2\">\u0627\u0644\u0625\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u0639\u0627\u062f\u0629 \u0643\u0641\u0631\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446652fc1.64069019\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446652fc1.64069019','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed175.mp3','80','false');show_hide('play','6a04d446652fc1.64069019');\" \/><input type=\"button\"  id=\"btnstop_6a04d446652fc1.64069019\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446652fc1.64069019','','80','false');show_hide('stop','6a04d446652fc1.64069019');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed175.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-177\">\n\t<td class=\"column-1\">176<\/td><td class=\"column-2\">\u0627\u0644\u0643\u0641\u0631 \u0627\u0644\u0648\u0627\u0636\u062d \u0644\u0627 \u064a\u0634\u062a\u0631\u0637 \u0641\u064a\u0647 \u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u062d\u062c\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446660a01.26185173\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446660a01.26185173','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed176.mp3','80','false');show_hide('play','6a04d446660a01.26185173');\" \/><input type=\"button\"  id=\"btnstop_6a04d446660a01.26185173\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446660a01.26185173','','80','false');show_hide('stop','6a04d446660a01.26185173');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed176.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-178\">\n\t<td class=\"column-1\">177<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0644\u0628\u0633 \u0627\u0644\u0642\u0644\u0627\u062f\u0629 \u0627\u0644\u062a\u064a \u0641\u064a\u0647\u0627 \u0635\u0648\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44666e3c6.10518993\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44666e3c6.10518993','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed177.mp3','80','false');show_hide('play','6a04d44666e3c6.10518993');\" \/><input type=\"button\"  id=\"btnstop_6a04d44666e3c6.10518993\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44666e3c6.10518993','','80','false');show_hide('stop','6a04d44666e3c6.10518993');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed177.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-179\">\n\t<td class=\"column-1\">178<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0627\u0646\u062a\u062d\u0627\u0631\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44667aa75.29344101\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44667aa75.29344101','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed178.mp3','80','false');show_hide('play','6a04d44667aa75.29344101');\" \/><input type=\"button\"  id=\"btnstop_6a04d44667aa75.29344101\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44667aa75.29344101','','80','false');show_hide('stop','6a04d44667aa75.29344101');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed178.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-180\">\n\t<td class=\"column-1\">179<\/td><td class=\"column-2\">\u0627\u0644\u0625\u0635\u0631\u0627\u0631 \u0639\u0644\u0649 \u0627\u0644\u0645\u0639\u0635\u064a\u0629 \u0644\u0627 \u064a\u062e\u0631\u062c \u0645\u0646 \u062f\u0627\u0626\u0631\u0629 \u0623\u0647\u0644 \u0627\u0644\u0633\u0646\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446686cc7.13942149\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446686cc7.13942149','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed179.mp3','80','false');show_hide('play','6a04d446686cc7.13942149');\" \/><input type=\"button\"  id=\"btnstop_6a04d446686cc7.13942149\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446686cc7.13942149','','80','false');show_hide('stop','6a04d446686cc7.13942149');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed179.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-181\">\n\t<td class=\"column-1\">180<\/td><td class=\"column-2\">\u0627\u0644\u0633\u0645\u0627\u0639 \u0641\u0642\u0637 \u0644\u0627\u0628\u0646 \u0639\u062b\u064a\u0645\u064a\u0646 \u0648\u0627\u0628\u0646 \u0628\u0627\u0632 \u0648\u0627\u0644\u0623\u0644\u0628\u0627\u0646\u064a \u0631\u062d\u0645\u0647\u0645 \u0627\u0644\u0644\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4466932f9.88154301\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4466932f9.88154301','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed180.mp3','80','false');show_hide('play','6a04d4466932f9.88154301');\" \/><input type=\"button\"  id=\"btnstop_6a04d4466932f9.88154301\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4466932f9.88154301','','80','false');show_hide('stop','6a04d4466932f9.88154301');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed180.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-182\">\n\t<td class=\"column-1\">181<\/td><td class=\"column-2\">\u0627\u0644\u0634\u064a\u062e \u0639\u0628\u062f\u0627\u0644\u0644\u0647 \u0627\u0644\u0628\u0633\u0627\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4466a08f8.90282182\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4466a08f8.90282182','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed181.mp3','80','false');show_hide('play','6a04d4466a08f8.90282182');\" \/><input type=\"button\"  id=\"btnstop_6a04d4466a08f8.90282182\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4466a08f8.90282182','','80','false');show_hide('stop','6a04d4466a08f8.90282182');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed181.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-183\">\n\t<td class=\"column-1\">182<\/td><td class=\"column-2\">\u0627\u0644\u0647\u062c\u0631\u0629 \u0628\u062f\u0648\u0646 \u0625\u0630\u0646 \u0627\u0644\u0648\u0644\u064a \u0627\u0644\u0645\u0633\u0644\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4466acd75.22140602\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4466acd75.22140602','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed182.mp3','80','false');show_hide('play','6a04d4466acd75.22140602');\" \/><input type=\"button\"  id=\"btnstop_6a04d4466acd75.22140602\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4466acd75.22140602','','80','false');show_hide('stop','6a04d4466acd75.22140602');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed182.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-184\">\n\t<td class=\"column-1\">183<\/td><td class=\"column-2\">\u062a\u0631\u0648\u064a\u062c \u0623\u0634\u0631\u0637\u0629 \u0639\u0645\u0631\u0648 \u062e\u0627\u0644\u062f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4466cdb75.57590508\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4466cdb75.57590508','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed183.mp3','80','false');show_hide('play','6a04d4466cdb75.57590508');\" \/><input type=\"button\"  id=\"btnstop_6a04d4466cdb75.57590508\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4466cdb75.57590508','','80','false');show_hide('stop','6a04d4466cdb75.57590508');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed183.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-185\">\n\t<td class=\"column-1\">184<\/td><td class=\"column-2\">\u062c\u0648\u0627\u0632 \u0627\u0644\u062a\u0633\u0645\u064a \u0628\u0627\u0644\u0633\u0644\u0641\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4466dd2e7.12043487\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4466dd2e7.12043487','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed184.mp3','80','false');show_hide('play','6a04d4466dd2e7.12043487');\" \/><input type=\"button\"  id=\"btnstop_6a04d4466dd2e7.12043487\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4466dd2e7.12043487','','80','false');show_hide('stop','6a04d4466dd2e7.12043487');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed184.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-186\">\n\t<td class=\"column-1\">185<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0627\u0644\u0645\u0638\u0627\u0647\u0631\u0627\u062a \u0644\u0645\u0635\u0644\u062d\u0629 \u0634\u0631\u0639\u064a\u0629 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4466eabe1.57860410\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4466eabe1.57860410','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed185.mp3','80','false');show_hide('play','6a04d4466eabe1.57860410');\" \/><input type=\"button\"  id=\"btnstop_6a04d4466eabe1.57860410\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4466eabe1.57860410','','80','false');show_hide('stop','6a04d4466eabe1.57860410');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed185.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-187\">\n\t<td class=\"column-1\">186<\/td><td class=\"column-2\">\u0633\u0624\u0627\u0644 \u0627\u0644\u0645\u063a\u0631\u0627\u0648\u064a \u0627\u0644\u062a\u0643\u0641\u064a\u0631\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4466ffce6.23136901\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4466ffce6.23136901','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed186.mp3','80','false');show_hide('play','6a04d4466ffce6.23136901');\" \/><input type=\"button\"  id=\"btnstop_6a04d4466ffce6.23136901\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4466ffce6.23136901','','80','false');show_hide('stop','6a04d4466ffce6.23136901');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed186.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-188\">\n\t<td class=\"column-1\">187<\/td><td class=\"column-2\">\u0641\u0627\u0644\u062d \u0628\u0646 \u0646\u0627\u0641\u0639 \u0627\u0644\u062d\u0631\u0628\u064a \u0648\u0627\u0644\u0634\u064a\u062e \u0631\u0628\u064a\u0639 \u0648\u0627\u0644\u062d\u0631\u0635 \u0639\u0644\u0649 \u062c\u0645\u0639 \u0643\u0644\u0645\u0629 \u0627\u0644\u0633\u0644\u0641\u064a\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44670db23.47111316\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44670db23.47111316','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed187.mp3','80','false');show_hide('play','6a04d44670db23.47111316');\" \/><input type=\"button\"  id=\"btnstop_6a04d44670db23.47111316\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44670db23.47111316','','80','false');show_hide('stop','6a04d44670db23.47111316');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed187.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-189\">\n\t<td class=\"column-1\">188<\/td><td class=\"column-2\">\u0643\u064a\u0641 \u062a\u0639\u0631\u0641 \u0627\u0644\u0645\u0631\u0623\u0629 \u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0631\u062c\u0644 \u0627\u0644\u0630\u064a \u064a\u0631\u064a\u062f \u0627\u0644\u0632\u0648\u0627\u062c \u0628\u0647\u0627 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44671d834.46906064\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44671d834.46906064','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed188.mp3','80','false');show_hide('play','6a04d44671d834.46906064');\" \/><input type=\"button\"  id=\"btnstop_6a04d44671d834.46906064\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44671d834.46906064','','80','false');show_hide('stop','6a04d44671d834.46906064');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed188.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-190\">\n\t<td class=\"column-1\">189<\/td><td class=\"column-2\">\u0645\u0646\u0647\u062c \u0623\u062d\u0645\u062f \u0633\u0644\u0627\u0651\u064e\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44672abf9.96615389\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44672abf9.96615389','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed189.mp3','80','false');show_hide('play','6a04d44672abf9.96615389');\" \/><input type=\"button\"  id=\"btnstop_6a04d44672abf9.96615389\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44672abf9.96615389','','80','false');show_hide('stop','6a04d44672abf9.96615389');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed189.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-191\">\n\t<td class=\"column-1\">190<\/td><td class=\"column-2\">\u0645\u0627 \u0645\u0639\u0646\u0649 \u0633\u0644\u0641\u064a \u0648\u0625\u0639\u0631\u0627\u0628\u0647\u0627 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446738f44.05590755\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446738f44.05590755','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed190.mp3','80','false');show_hide('play','6a04d446738f44.05590755');\" \/><input type=\"button\"  id=\"btnstop_6a04d446738f44.05590755\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446738f44.05590755','','80','false');show_hide('stop','6a04d446738f44.05590755');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed190.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-192\">\n\t<td class=\"column-1\">191<\/td><td class=\"column-2\">\u0644\u0627 \u062a\u062c\u0648\u0632 \u0627\u0644\u0625\u0642\u0627\u0645\u0629 \u0641\u064a \u0628\u0644\u0627\u062f \u0627\u0644\u0643\u0641\u0631 \u0625\u0644\u0627 \u0627\u0644\u0645\u0633\u062a\u0636\u0639\u0641\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467464a6.57684952\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467464a6.57684952','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed191.mp3','80','false');show_hide('play','6a04d4467464a6.57684952');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467464a6.57684952\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467464a6.57684952','','80','false');show_hide('stop','6a04d4467464a6.57684952');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed191.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-193\">\n\t<td class=\"column-1\">192<\/td><td class=\"column-2\">\u0645\u0646 \u0645\u0646\u0647\u062c \u0627\u0644\u0633\u0644\u0641 \u062a\u0643\u0631\u0627\u0631 \u0627\u0644\u0646\u0635\u064a\u062d\u0629 \u0644\u0644\u0645\u062e\u0637\u0626<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44675a9e4.95693567\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44675a9e4.95693567','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed192.mp3','80','false');show_hide('play','6a04d44675a9e4.95693567');\" \/><input type=\"button\"  id=\"btnstop_6a04d44675a9e4.95693567\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44675a9e4.95693567','','80','false');show_hide('stop','6a04d44675a9e4.95693567');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed192.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-194\">\n\t<td class=\"column-1\">193<\/td><td class=\"column-2\">\u0645\u062a\u0649 \u064a\u062d\u0630\u0631 \u0645\u0646 \u0627\u0644\u0634\u062e\u0635 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446769791.32303020\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446769791.32303020','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed193.mp3','80','false');show_hide('play','6a04d446769791.32303020');\" \/><input type=\"button\"  id=\"btnstop_6a04d446769791.32303020\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446769791.32303020','','80','false');show_hide('stop','6a04d446769791.32303020');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed193.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-195\">\n\t<td class=\"column-1\">194<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0645\u0646 \u0623\u0631\u0627\u062f \u0623\u0646 \u064a\u062e\u062a\u0628\u0631 \u064a\u0642\u0631\u0623 \" \u0643\u0647\u064a\u0639\u0635 \" \u062d\u062a\u0649 \u064a\u0646\u062c\u062d<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446778258.67523666\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446778258.67523666','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed194.mp3','80','false');show_hide('play','6a04d446778258.67523666');\" \/><input type=\"button\"  id=\"btnstop_6a04d446778258.67523666\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446778258.67523666','','80','false');show_hide('stop','6a04d446778258.67523666');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed194.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-196\">\n\t<td class=\"column-1\">195<\/td><td class=\"column-2\">\u0627\u0644\u0623\u0641\u0636\u0644 \u0639\u062f\u0645 \u0627\u0644\u062a\u0639\u0644\u0645 \u0639\u0644\u0649 \u0623\u064a\u062f\u064a \u0627\u0644\u0645\u0628\u062a\u062f\u0639\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446785f49.54134531\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446785f49.54134531','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed195.mp3','80','false');show_hide('play','6a04d446785f49.54134531');\" \/><input type=\"button\"  id=\"btnstop_6a04d446785f49.54134531\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446785f49.54134531','','80','false');show_hide('stop','6a04d446785f49.54134531');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed195.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-197\">\n\t<td class=\"column-1\">196<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0648\u0633\u0644 \u0628\u062c\u0627\u0647 \u0627\u0644\u0631\u0633\u0648\u0644 \ufdfa \u0628\u062f\u0639\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446793739.90543933\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446793739.90543933','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed196.mp3','80','false');show_hide('play','6a04d446793739.90543933');\" \/><input type=\"button\"  id=\"btnstop_6a04d446793739.90543933\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446793739.90543933','','80','false');show_hide('stop','6a04d446793739.90543933');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed196.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-198\">\n\t<td class=\"column-1\">197<\/td><td class=\"column-2\">\u0627\u0644\u0639\u0627\u0645\u064a \u0627\u0644\u0630\u064a \u064a\u062f\u0627\u0641\u0639 \u0639\u0646 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639 \u064a\u0644\u062d\u0642 \u0628\u0647\u0645 \u0628\u0639\u062f \u0627\u0644\u0646\u0635\u064a\u062d\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467a0944.47667816\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467a0944.47667816','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed197.mp3','80','false');show_hide('play','6a04d4467a0944.47667816');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467a0944.47667816\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467a0944.47667816','','80','false');show_hide('stop','6a04d4467a0944.47667816');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed197.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-199\">\n\t<td class=\"column-1\">198<\/td><td class=\"column-2\">\u0639\u0627\u0626\u0636 \u0627\u0644\u0642\u0631\u0646\u064a \u0648\u0627\u0644\u062f\u0648\u064a\u0634 \u0648\u0627\u0644\u0639\u0631\u064a\u0641\u064a \u0643\u0644\u0647\u0645 \u062d\u0632\u0628\u064a\u0648\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467ae470.79413489\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467ae470.79413489','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed198.mp3','80','false');show_hide('play','6a04d4467ae470.79413489');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467ae470.79413489\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467ae470.79413489','','80','false');show_hide('stop','6a04d4467ae470.79413489');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed198.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-200\">\n\t<td class=\"column-1\">199<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0639\u0644\u064a \u062c\u0645\u0639\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467baef8.75270137\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467baef8.75270137','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed199.mp3','80','false');show_hide('play','6a04d4467baef8.75270137');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467baef8.75270137\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467baef8.75270137','','80','false');show_hide('stop','6a04d4467baef8.75270137');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed199.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-201\">\n\t<td class=\"column-1\">200<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646 \u0627\u0644\u0645\u063a\u0631\u0648\u0627\u064a \u0639\u0627\u0644\u0645 \u0633\u0646\u064a \u0648\u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646 \u0627\u0644\u0634\u064a\u062e \u0627\u0644\u0631\u0628\u064a\u0639 \u064a\u0631\u0649 \u0623\u0646 \u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0645\u0643\u0645\u0644\u0627\u062a \u0648\u0627\u0646\u0647\u0627 \u0644\u064a\u0633\u062a \u0645\u0646 \u0627\u0644\u0623\u0635\u0648\u0644<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467caa34.64102589\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467caa34.64102589','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed200.mp3','80','false');show_hide('play','6a04d4467caa34.64102589');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467caa34.64102589\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467caa34.64102589','','80','false');show_hide('stop','6a04d4467caa34.64102589');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed200.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-202\">\n\t<td class=\"column-1\">201<\/td><td class=\"column-2\">\u062c\u0648\u0627\u0632 \u0633\u0624\u0627\u0644 \u0627\u0644\u0648\u0644\u0627\u064a\u0629 \u0644\u0645\u0646 \u064a\u0631\u064a\u062f \u062a\u062d\u0643\u064a\u0645 \u0627\u0644\u0634\u0631\u064a\u0639\u0629 \u0648\u0643\u0627\u0646 \u0623\u0647\u0644\u0627 \u0644\u0647\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467d8f71.29429198\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467d8f71.29429198','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed201.mp3','80','false');show_hide('play','6a04d4467d8f71.29429198');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467d8f71.29429198\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467d8f71.29429198','','80','false');show_hide('stop','6a04d4467d8f71.29429198');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed201.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-203\">\n\t<td class=\"column-1\">202<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0646 \u0627\u0644\u0644\u0647 \u0628\u0630\u0627\u062a\u0647 \u0641\u064a \u0643\u0644 \u0645\u0643\u0627\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467e7343.15973990\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467e7343.15973990','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed202.mp3','80','false');show_hide('play','6a04d4467e7343.15973990');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467e7343.15973990\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467e7343.15973990','','80','false');show_hide('stop','6a04d4467e7343.15973990');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed202.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-204\">\n\t<td class=\"column-1\">203<\/td><td class=\"column-2\">\u0647\u0644 \u0627\u062e\u062a\u0644\u0641 \u0639\u0644\u0645\u0627\u0621 \u0627\u0644\u0633\u0646\u0629 \u0641\u064a \u0625\u062b\u0628\u0627\u062a \u0627\u0644\u0645\u0643\u0627\u0646 \u0644\u0644\u0647 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4467f4e63.12795276\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4467f4e63.12795276','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed203.mp3','80','false');show_hide('play','6a04d4467f4e63.12795276');\" \/><input type=\"button\"  id=\"btnstop_6a04d4467f4e63.12795276\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4467f4e63.12795276','','80','false');show_hide('stop','6a04d4467f4e63.12795276');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed203.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-205\">\n\t<td class=\"column-1\">204<\/td><td class=\"column-2\">\u0647\u0644 \u0627\u0644\u0623\u0631\u0636 \u0642\u0631\u0627\u0631 \u0644\u0627 \u062a\u062a\u062d\u0631\u0643 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446801e43.98128645\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446801e43.98128645','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed204.mp3','80','false');show_hide('play','6a04d446801e43.98128645');\" \/><input type=\"button\"  id=\"btnstop_6a04d446801e43.98128645\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446801e43.98128645','','80','false');show_hide('stop','6a04d446801e43.98128645');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed204.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-206\">\n\t<td class=\"column-1\">205<\/td><td class=\"column-2\">\u0647\u0644 \u0627\u0644\u0623\u0631\u0636 \u0647\u064a \u0645\u0631\u0643\u0632 \u0627\u0644\u0639\u0627\u0644\u0645 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468101a6.17635802\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468101a6.17635802','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed205.mp3','80','false');show_hide('play','6a04d4468101a6.17635802');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468101a6.17635802\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468101a6.17635802','','80','false');show_hide('stop','6a04d4468101a6.17635802');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed205.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-207\">\n\t<td class=\"column-1\">206<\/td><td class=\"column-2\">\u0647\u0644 \u0648\u0631\u062f \u0641\u064a \u0627\u0644\u0643\u062a\u0627\u0628 \u0648\u0627\u0644\u0633\u0646\u0629 \u0623\u0646 \u0627\u0644\u0644\u0647 \u0641\u064a \u062c\u0647\u0629 \u0639\u062f\u0645\u064a\u0629 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44681d732.97953968\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44681d732.97953968','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed206.mp3','80','false');show_hide('play','6a04d44681d732.97953968');\" \/><input type=\"button\"  id=\"btnstop_6a04d44681d732.97953968\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44681d732.97953968','','80','false');show_hide('stop','6a04d44681d732.97953968');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed206.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-208\">\n\t<td class=\"column-1\">207<\/td><td class=\"column-2\">\u0627\u062a\u062e\u0627\u0630 \u0627\u0644\u0633\u0643\u0648\u062a \u0639\u0644\u0649 \u0623\u062e\u0637\u0627\u0621 \u0627\u0644\u062c\u0645\u0627\u0639\u0627\u062a \u0627\u0644\u062d\u0632\u0628\u064a\u0629 \u0627\u0644\u0645\u0639\u0627\u0635\u0631\u0629 \u0645\u0646\u0647\u062c\u0627\u064b \u0648\u0627\u0644\u0632\u0639\u0645 \u0628\u0623\u0646\u0647\u0627 \u0627\u0644\u062d\u0643\u0645\u0629 \u0648\u0637\u0631\u0642 \u0645\u062d\u0627\u0631\u0628\u062a\u0647\u0645 \u0644\u0639\u0644\u0645\u0627\u0621 \u0627\u0644\u0633\u0644\u0641<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44682bf32.91791956\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44682bf32.91791956','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed207.mp3','80','false');show_hide('play','6a04d44682bf32.91791956');\" \/><input type=\"button\"  id=\"btnstop_6a04d44682bf32.91791956\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44682bf32.91791956','','80','false');show_hide('stop','6a04d44682bf32.91791956');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed207.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-209\">\n\t<td class=\"column-1\">208<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0632\u0647\u062f \u0641\u064a \u0643\u062a\u0628 \u0627\u0644\u0633\u0644\u0641 \u0648\u064a\u0631\u0649 \u0623\u0646 \u0643\u062a\u0628 \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0643\u062a\u0628\u062a \u0644\u063a\u064a\u0631 \u0647\u0630\u0627 \u0627\u0644\u0639\u0635\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446837e01.99965057\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446837e01.99965057','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed208.mp3','80','false');show_hide('play','6a04d446837e01.99965057');\" \/><input type=\"button\"  id=\"btnstop_6a04d446837e01.99965057\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446837e01.99965057','','80','false');show_hide('stop','6a04d446837e01.99965057');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed208.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-210\">\n\t<td class=\"column-1\">209<\/td><td class=\"column-2\">\u0628\u0637\u0644\u0627\u0646 \u0645\u0642\u0627\u0644\u0629 : \" \u0627\u0644\u0633\u0643\u0648\u062a \u0639\u0646 \u0623\u0647\u0644 \u0627\u0644\u0628\u062f\u0639 \u0645\u0646 \u0623\u062c\u0644 \u0645\u0635\u0644\u062d\u0629 \u0627\u0644\u062f\u0639\u0648\u0629 \"<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468464d3.08619403\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468464d3.08619403','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed209.mp3','80','false');show_hide('play','6a04d4468464d3.08619403');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468464d3.08619403\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468464d3.08619403','','80','false');show_hide('stop','6a04d4468464d3.08619403');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed209.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-211\">\n\t<td class=\"column-1\">210<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u062a\u0647\u0645 \u0627\u0644\u0623\u0626\u0645\u0629 \u0627\u0644\u062b\u0644\u0627\u062b\u0629 \u0627\u0628\u0646 \u0628\u0627\u0632 \u0648\u0627\u0628\u0646 \u0639\u062b\u064a\u0645\u064a\u0646 \u0648\u0627\u0644\u0623\u0644\u0628\u0627\u0646\u064a \u0628\u0627\u0644\u0625\u0631\u062c\u0627\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446853564.42120013\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446853564.42120013','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed210.mp3','80','false');show_hide('play','6a04d446853564.42120013');\" \/><input type=\"button\"  id=\"btnstop_6a04d446853564.42120013\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446853564.42120013','','80','false');show_hide('stop','6a04d446853564.42120013');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed210.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-212\">\n\t<td class=\"column-1\">211<\/td><td class=\"column-2\">\u0627\u0644\u0625\u0635\u0631\u0627\u0631 \u0639\u0644\u0649 \u0645\u062e\u0627\u0644\u0641\u0629 \u0628\u064a\u0627\u0646 \u0633\u0645\u0627\u062d\u0629 \u0627\u0644\u0645\u0641\u062a\u064a \u0628\u062a\u0631\u0634\u064a\u062f \u0627\u0644\u0641\u062a\u0648\u0649 \u0639\u0628\u0631 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446861c18.58748064\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446861c18.58748064','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed211.mp3','80','false');show_hide('play','6a04d446861c18.58748064');\" \/><input type=\"button\"  id=\"btnstop_6a04d446861c18.58748064\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446861c18.58748064','','80','false');show_hide('stop','6a04d446861c18.58748064');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed211.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-213\">\n\t<td class=\"column-1\">212<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0627\u0644\u062a\u0646\u0642\u0651\u064f\u0635 \u0644\u0644\u0639\u0644\u0645\u0627\u0621 \u0648\u0648\u0644\u0627\u0629 \u0627\u0644\u0623\u0645\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44686ce76.19808189\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44686ce76.19808189','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed212.mp3','80','false');show_hide('play','6a04d44686ce76.19808189');\" \/><input type=\"button\"  id=\"btnstop_6a04d44686ce76.19808189\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44686ce76.19808189','','80','false');show_hide('stop','6a04d44686ce76.19808189');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed212.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-214\">\n\t<td class=\"column-1\">213<\/td><td class=\"column-2\">\u0633\u064a\u062f \u0642\u0637\u0628 \u0644\u064a\u0633 \u0645\u0646 \u0623\u0647\u0644 \u0627\u0644\u0633\u0646\u0629 \u0648\u0627\u0644\u062c\u0645\u0627\u0639\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446878b50.78629950\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446878b50.78629950','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed213.mp3','80','false');show_hide('play','6a04d446878b50.78629950');\" \/><input type=\"button\"  id=\"btnstop_6a04d446878b50.78629950\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446878b50.78629950','','80','false');show_hide('stop','6a04d446878b50.78629950');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed213.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-215\">\n\t<td class=\"column-1\">214<\/td><td class=\"column-2\">\u0645\u0627 \u0631\u0623\u064a\u0643\u0645 \u0641\u064a\u0645\u0646 \u064a\u062d\u0630\u0631 \u0645\u0646 \u0627\u0644\u0628\u062f\u0639\u0629 \u0648\u0627\u0644\u0645\u0628\u062a\u062f\u0639\u0629 \u0648\u0644\u0627 \u064a\u0631\u0649 \u0630\u0643\u0631 \u0627\u0644\u0623\u0633\u0645\u0627\u0621<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446884d32.38570786\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446884d32.38570786','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed214.mp3','80','false');show_hide('play','6a04d446884d32.38570786');\" \/><input type=\"button\"  id=\"btnstop_6a04d446884d32.38570786\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446884d32.38570786','','80','false');show_hide('stop','6a04d446884d32.38570786');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed214.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-216\">\n\t<td class=\"column-1\">215<\/td><td class=\"column-2\">\u0645\u0627 \u062d\u0643\u0645 \u0627\u0644\u062c\u0647\u0627\u062f \u0641\u064a \u0633\u0628\u064a\u0644 \u0627\u0644\u0644\u0647 \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0623\u064a\u0627\u0645 \u0648\u0647\u0644 \u064a\u0644\u0632\u0645 \u0627\u0644\u0625\u0630\u0646 \u0645\u0646 \u0648\u0644\u064a \u0627\u0644\u0623\u0645\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468906c1.78712837\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468906c1.78712837','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed215.mp3','80','false');show_hide('play','6a04d4468906c1.78712837');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468906c1.78712837\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468906c1.78712837','','80','false');show_hide('stop','6a04d4468906c1.78712837');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed215.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-217\">\n\t<td class=\"column-1\">216<\/td><td class=\"column-2\">\u0628\u0639\u0636 \u0645\u062e\u0627\u0644\u0641\u0627\u062a \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0648\u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u062a\u0628\u0644\u064a\u063a \u0648\u0623\u0646\u0647\u0645 \u0645\u0646 \u0627\u0644\u0641\u0631\u0642 \u0627\u0644\u0647\u0627\u0644\u0643\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44689cc30.10687528\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44689cc30.10687528','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed216.mp3','80','false');show_hide('play','6a04d44689cc30.10687528');\" \/><input type=\"button\"  id=\"btnstop_6a04d44689cc30.10687528\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44689cc30.10687528','','80','false');show_hide('stop','6a04d44689cc30.10687528');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed216.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-218\">\n\t<td class=\"column-1\">217<\/td><td class=\"column-2\">\u0645\u0627 \u0645\u0639\u0646\u0649 \u0642\u0648\u0644 \" \u0627\u0644\u0627\u062c\u062a\u0647\u0627\u062f \u0645\u0645\u0646 \u0647\u0645 \u0645\u0646 \u0623\u0647\u0644 \u0627\u0644\u0644\u0633\u0627\u0646 \"<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468a9051.78183246\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468a9051.78183246','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed217.mp3','80','false');show_hide('play','6a04d4468a9051.78183246');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468a9051.78183246\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468a9051.78183246','','80','false');show_hide('stop','6a04d4468a9051.78183246');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed217.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-219\">\n\t<td class=\"column-1\">218<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0628\u0639\u0636 \u0623\u0641\u0631\u0627\u062f \u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u062a\u0628\u0644\u064a\u063a \u0628\u0627\u062d\u062a\u062c\u0627\u062c\u0647\u0645 \u0628\u062b\u0646\u0627\u0621 \u0628\u0639\u0636 \u0627\u0644\u0639\u0644\u0645\u0627\u0621 \u0639\u0644\u064a\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468b7ad1.51073350\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468b7ad1.51073350','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed218.mp3','80','false');show_hide('play','6a04d4468b7ad1.51073350');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468b7ad1.51073350\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468b7ad1.51073350','','80','false');show_hide('stop','6a04d4468b7ad1.51073350');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed218.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-220\">\n\t<td class=\"column-1\">219<\/td><td class=\"column-2\">\u0641\u062a\u0627\u0648\u0649 : \u0645\u0627 \u062d\u0643\u0645 \u0627\u0644\u062f\u0639\u0648\u0629 \u0644\u0644\u0645\u0638\u0627\u0647\u0631\u0627\u062a \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468c53f6.45698924\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468c53f6.45698924','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed219.mp3','80','false');show_hide('play','6a04d4468c53f6.45698924');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468c53f6.45698924\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468c53f6.45698924','','80','false');show_hide('stop','6a04d4468c53f6.45698924');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed219.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-221\">\n\t<td class=\"column-1\">220<\/td><td class=\"column-2\">\u0641\u062a\u0627\u0648\u0649 : \u0647\u0644 \u064a\u0641\u0647\u0645 \u0645\u0646 \u0642\u0648\u0644 \u0634\u064a\u062e \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0623\u0646\u0647 \u0644\u0627 \u064a\u062c\u0648\u0632 \u0637\u0644\u0628 \u0627\u0644\u0639\u0644\u0645 \u062d\u062a\u0649 \u064a\u064f\u0639\u0631\u0641 \u062d\u0627\u0644 \u0627\u0644\u0634\u062e\u0635 \u0648\u0643\u0630\u0644\u0643 \u0639\u0646\u062f \u0625\u0644\u0642\u0627\u0621 \u0627\u0644\u0633\u0644\u0627\u0645 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468d3a17.46881531\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468d3a17.46881531','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed220.mp3','80','false');show_hide('play','6a04d4468d3a17.46881531');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468d3a17.46881531\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468d3a17.46881531','','80','false');show_hide('stop','6a04d4468d3a17.46881531');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed220.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-222\">\n\t<td class=\"column-1\">221<\/td><td class=\"column-2\">\u0641\u062a\u0627\u0648\u0649 : \u0647\u0644 \u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u062a\u0628\u0644\u064a\u063a \u0639\u0644\u0649 \u0627\u0644\u0645\u0646\u0647\u062c \u0627\u0644\u0633\u0644\u0641\u064a \u0648\u0647\u0644 \u062a\u0646\u0635\u062d\u0648\u0646 \u0627\u0644\u0634\u0628\u0627\u0628 \u0628\u0627\u0644\u062e\u0631\u0648\u062c \u0645\u0639\u0647\u0645 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468e2452.14912078\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468e2452.14912078','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed221.mp3','80','false');show_hide('play','6a04d4468e2452.14912078');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468e2452.14912078\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468e2452.14912078','','80','false');show_hide('stop','6a04d4468e2452.14912078');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed221.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-223\">\n\t<td class=\"column-1\">222<\/td><td class=\"column-2\">\u0641\u062a\u0627\u0648\u0649 : \u0645\u0627 \u0642\u0648\u0644\u0643\u0645 \u0641\u064a \u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u061f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468f1183.25747540\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468f1183.25747540','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed222.mp3','80','false');show_hide('play','6a04d4468f1183.25747540');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468f1183.25747540\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468f1183.25747540','','80','false');show_hide('stop','6a04d4468f1183.25747540');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed222.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-224\">\n\t<td class=\"column-1\">223<\/td><td class=\"column-2\">\u0641\u062a\u0627\u0648\u0649 : \u0645\u0627 \u0647\u0648 \u0645\u0630\u0647\u0628 \u0627\u0644\u0633\u0644\u0641 \u0641\u064a \u0645\u0646\u0627\u0635\u062d\u0629 \u0648\u0644\u0627\u0629 \u0627\u0644\u0623\u0645\u0631 \u0648\u0627\u0644\u0625\u0646\u0643\u0627\u0631 \u0639\u0644\u064a\u0647\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4468fe8f7.22295777\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4468fe8f7.22295777','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed223.mp3','80','false');show_hide('play','6a04d4468fe8f7.22295777');\" \/><input type=\"button\"  id=\"btnstop_6a04d4468fe8f7.22295777\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4468fe8f7.22295777','','80','false');show_hide('stop','6a04d4468fe8f7.22295777');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed223.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-225\">\n\t<td class=\"column-1\">224<\/td><td class=\"column-2\">\u0645\u0627 \u0633\u0628\u0628 \u062a\u0642\u0633\u064a\u0645 \u0627\u0644\u0639\u0644\u0645\u0627\u0621 \u0628\u064a\u0646 \u0627\u0644\u0634\u0631\u0643 \u0627\u0644\u0623\u0643\u0628\u0631 \u0648\u0627\u0644\u0634\u0631\u0643 \u0627\u0644\u0623\u0635\u063a\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44690cc36.96771897\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44690cc36.96771897','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed224.mp3','80','false');show_hide('play','6a04d44690cc36.96771897');\" \/><input type=\"button\"  id=\"btnstop_6a04d44690cc36.96771897\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44690cc36.96771897','','80','false');show_hide('stop','6a04d44690cc36.96771897');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed224.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-226\">\n\t<td class=\"column-1\">225<\/td><td class=\"column-2\">\u0627\u0644\u0645\u0646\u0647\u062c \u0627\u0644\u0633\u0644\u0641\u064a \u0641\u064a \u0627\u0644\u062f\u0639\u0648\u0629 \u0625\u0644\u0649 \u0627\u0644\u0644\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44691bf67.46112157\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44691bf67.46112157','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed225.mp3','80','false');show_hide('play','6a04d44691bf67.46112157');\" \/><input type=\"button\"  id=\"btnstop_6a04d44691bf67.46112157\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44691bf67.46112157','','80','false');show_hide('stop','6a04d44691bf67.46112157');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed225.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-227\">\n\t<td class=\"column-1\">226<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0628\u0639\u062f\u0645 \u0627\u0644\u062a\u0631\u062d\u0645 \u0639\u0644\u0649 \u0627\u0644\u0646\u0648\u0648\u064a \u0648\u0627\u0628\u0646 \u062d\u062c\u0631 \u0648\u0623\u0628\u0648 \u062d\u0646\u064a\u0641\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446933564.96541736\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446933564.96541736','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed226.mp3','80','false');show_hide('play','6a04d446933564.96541736');\" \/><input type=\"button\"  id=\"btnstop_6a04d446933564.96541736\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446933564.96541736','','80','false');show_hide('stop','6a04d446933564.96541736');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed226.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-228\">\n\t<td class=\"column-1\">227<\/td><td class=\"column-2\">\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u062d\u0627\u0641\u0638 \u0627\u0628\u0646 \u062d\u062c\u0631 \u0648\u0633\u064a\u062f \u0642\u0637\u0628<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446948858.82268770\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446948858.82268770','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed227.mp3','80','false');show_hide('play','6a04d446948858.82268770');\" \/><input type=\"button\"  id=\"btnstop_6a04d446948858.82268770\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446948858.82268770','','80','false');show_hide('stop','6a04d446948858.82268770');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed227.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-229\">\n\t<td class=\"column-1\">228<\/td><td class=\"column-2\">\u0639\u062f\u0645 \u0627\u0644\u0639\u0630\u0631 \u0628\u062a\u0631\u0643 \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0635\u062d\u064a\u062d\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446957d03.39902857\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446957d03.39902857','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed228.mp3','80','false');show_hide('play','6a04d446957d03.39902857');\" \/><input type=\"button\"  id=\"btnstop_6a04d446957d03.39902857\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446957d03.39902857','','80','false');show_hide('stop','6a04d446957d03.39902857');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed228.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-230\">\n\t<td class=\"column-1\">229<\/td><td class=\"column-2\">\u0627\u0644\u062a\u0645\u062b\u064a\u0644 \u0648\u0627\u0644\u0623\u0646\u0627\u0634\u064a\u062f \u0644\u064a\u0633\u062a \u0645\u0646 \u0623\u0633\u0627\u0644\u064a\u0628 \u0627\u0644\u062f\u0639\u0648\u0629 \u0627\u0644\u0633\u0644\u0641\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446965a06.99571268\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446965a06.99571268','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed229.mp3','80','false');show_hide('play','6a04d446965a06.99571268');\" \/><input type=\"button\"  id=\"btnstop_6a04d446965a06.99571268\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446965a06.99571268','','80','false');show_hide('stop','6a04d446965a06.99571268');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed229.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-231\">\n\t<td class=\"column-1\">230<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0645\u0646 \u0644\u0645 \u064a\u0628\u062f\u0639 \u0627\u0644\u0645\u0628\u062a\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d446974f93.95480798\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d446974f93.95480798','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed230.mp3','80','false');show_hide('play','6a04d446974f93.95480798');\" \/><input type=\"button\"  id=\"btnstop_6a04d446974f93.95480798\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d446974f93.95480798','','80','false');show_hide('stop','6a04d446974f93.95480798');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed230.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-232\">\n\t<td class=\"column-1\">231<\/td><td class=\"column-2\">\u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u062d\u062c\u0629 \u0639\u0644\u0649 \u0627\u0644\u0645\u0628\u062a\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469826d7.21992876\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469826d7.21992876','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed231.mp3','80','false');show_hide('play','6a04d4469826d7.21992876');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469826d7.21992876\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469826d7.21992876','','80','false');show_hide('stop','6a04d4469826d7.21992876');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed231.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-233\">\n\t<td class=\"column-1\">232<\/td><td class=\"column-2\">\u0627\u0644\u0628\u064a\u0639\u0629 \u0627\u0644\u0633\u0631\u064a\u0629 \u0644\u063a\u064a\u0631 \u0625\u0645\u0627\u0645 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469922a5.42064735\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469922a5.42064735','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed232.mp3','80','false');show_hide('play','6a04d4469922a5.42064735');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469922a5.42064735\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469922a5.42064735','','80','false');show_hide('stop','6a04d4469922a5.42064735');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed232.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-234\">\n\t<td class=\"column-1\">233<\/td><td class=\"column-2\">\u062d\u0642\u064a\u0642\u0629 \u062a\u0648\u062d\u064a\u062f \u0627\u0644\u062d\u0627\u0643\u0645\u064a\u0629 \u0648\u0644\u0645\u0627\u0630\u0627 \u064a\u0642\u0627\u0644 \u0639\u0646\u0647 \u062a\u0648\u062d\u064a\u062f \u0627\u0644\u0645\u062a\u0627\u0628\u0639\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469a1a45.12117613\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469a1a45.12117613','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed233.mp3','80','false');show_hide('play','6a04d4469a1a45.12117613');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469a1a45.12117613\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469a1a45.12117613','','80','false');show_hide('stop','6a04d4469a1a45.12117613');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed233.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-235\">\n\t<td class=\"column-1\">234<\/td><td class=\"column-2\">\u0627\u0644\u0635\u062d\u0627\u0628\u0629 \u0631\u0636\u0648\u0627\u0646 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647\u0645 \u0644\u0645 \u062a\u0638\u0647\u0631 \u0641\u064a\u0647\u0645 \u0627\u0644\u0628\u062f\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469b0060.54692212\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469b0060.54692212','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed234.mp3','80','false');show_hide('play','6a04d4469b0060.54692212');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469b0060.54692212\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469b0060.54692212','','80','false');show_hide('stop','6a04d4469b0060.54692212');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed234.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-236\">\n\t<td class=\"column-1\">235<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u064f\u0632\u0647\u0651\u0650\u062f \u0641\u064a \u0643\u062a\u0628 \u0627\u0644\u0631\u062f\u0648\u062f<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469be6d4.99340841\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469be6d4.99340841','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed235.mp3','80','false');show_hide('play','6a04d4469be6d4.99340841');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469be6d4.99340841\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469be6d4.99340841','','80','false');show_hide('stop','6a04d4469be6d4.99340841');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed235.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-237\">\n\t<td class=\"column-1\">236<\/td><td class=\"column-2\">\u0645\u0646\u0647\u062c \u0627\u0644\u0633\u0644\u0641 \u0641\u064a \u0627\u0644\u0625\u0646\u0643\u0627\u0631 \u0639\u0644\u0649 \u0648\u0644\u0627\u0629 \u0627\u0644\u0623\u0645\u0648\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469cc017.58296828\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469cc017.58296828','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed236.mp3','80','false');show_hide('play','6a04d4469cc017.58296828');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469cc017.58296828\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469cc017.58296828','','80','false');show_hide('stop','6a04d4469cc017.58296828');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed236.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-238\">\n\t<td class=\"column-1\">237<\/td><td class=\"column-2\">\u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u062d\u062c\u0629 \u0639\u0644\u0649 \u0645\u0646 \u0623\u062e\u0637\u0623 \u0641\u064a \u0645\u0633\u0623\u0644\u0629 \u0645\u0646\u0647\u062c\u064a\u0629 \u0623\u0648 \u0639\u0642\u062f\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469d8793.62646810\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469d8793.62646810','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed237.mp3','80','false');show_hide('play','6a04d4469d8793.62646810');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469d8793.62646810\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469d8793.62646810','','80','false');show_hide('stop','6a04d4469d8793.62646810');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed237.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-239\">\n\t<td class=\"column-1\">238<\/td><td class=\"column-2\">\u0646\u0635\u064a\u062d\u0629 \u0644\u0645\u0646 \u064a\u0639\u062a\u0642\u062f \u0641\u064a \u0627\u0644\u0645\u062e\u0644\u0648\u0642\u064a\u0646 \u0642\u062f\u0631\u062a\u0647\u0645 \u0639\u0644\u0649 \u0627\u0644\u0623\u0641\u0639\u0627\u0644 \u0627\u0644\u062a\u064a \u0644\u0627 \u064a\u0642\u062f\u0631 \u0639\u0644\u064a\u0647\u0627 \u0625\u0644\u0627 \u0627\u0644\u0644\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469e48f9.64382092\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469e48f9.64382092','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed238.mp3','80','false');show_hide('play','6a04d4469e48f9.64382092');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469e48f9.64382092\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469e48f9.64382092','','80','false');show_hide('stop','6a04d4469e48f9.64382092');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed238.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-240\">\n\t<td class=\"column-1\">239<\/td><td class=\"column-2\">\u062f\u0639\u0648\u0629 \u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0648\u0623\u062b\u0631\u0647\u0627 \u0641\u064a \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u0625\u0631\u0647\u0627\u0628\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469f1e65.32703297\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469f1e65.32703297','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed239.mp3','80','false');show_hide('play','6a04d4469f1e65.32703297');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469f1e65.32703297\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469f1e65.32703297','','80','false');show_hide('stop','6a04d4469f1e65.32703297');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed239.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-241\">\n\t<td class=\"column-1\">240<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0623\u0633\u0642\u0637\u0648\u0627 \u0627\u0644\u0645\u0646\u0627\u0647\u062c \u0648\u0644\u0627 \u062f\u0627\u0639\u064a \u0644\u0630\u0643\u0631 \u0627\u0644\u0623\u0634\u062e\u0627\u0635<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d4469fe8e5.60614830\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d4469fe8e5.60614830','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed240.mp3','80','false');show_hide('play','6a04d4469fe8e5.60614830');\" \/><input type=\"button\"  id=\"btnstop_6a04d4469fe8e5.60614830\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d4469fe8e5.60614830','','80','false');show_hide('stop','6a04d4469fe8e5.60614830');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed240.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-242\">\n\t<td class=\"column-1\">241<\/td><td class=\"column-2\">\u0627\u0644\u062f\u0639\u0648\u0629 \u0625\u0644\u0649 \u0627\u0644\u0644\u0647 \u0645\u0628\u0646\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0639\u0644\u0645 \u0627\u0644\u0634\u0631\u0639\u064a \u0644\u0627 \u0639\u0644\u0648\u0645 \u0627\u0644\u0622\u0644\u0629<\/td><td class=\"column-3\"><div style=\"color:red;font-weight:bold;\">Requested file could not be found (error code 404). Verify the file URL specified in the shortcode.<\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed241.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-243\">\n\t<td class=\"column-1\">242<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0625\u0631\u0627\u062f\u0629 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0628\u0639\u0645\u0644\u0647 \u0627\u0644\u062f\u0646\u064a\u0627<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dbfb299.96519878\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dbfb299.96519878','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed242.mp3','80','false');show_hide('play','6a04d44dbfb299.96519878');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dbfb299.96519878\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dbfb299.96519878','','80','false');show_hide('stop','6a04d44dbfb299.96519878');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed242.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-244\">\n\t<td class=\"column-1\">243<\/td><td class=\"column-2\">\u0627\u0644\u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0639\u0644\u0649 \u0645\u0646\u0647\u062c \u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dc12eb5.00841730\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dc12eb5.00841730','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed243.mp3','80','false');show_hide('play','6a04d44dc12eb5.00841730');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dc12eb5.00841730\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dc12eb5.00841730','','80','false');show_hide('stop','6a04d44dc12eb5.00841730');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed243.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-245\">\n\t<td class=\"column-1\">244<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0627\u0644\u0635\u0648\u0641\u064a\u0629 \u0648\u0627\u0644\u0627\u0634\u062a\u0631\u0627\u0643\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dc29117.11075502\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dc29117.11075502','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f244.mp3','80','false');show_hide('play','6a04d44dc29117.11075502');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dc29117.11075502\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dc29117.11075502','','80','false');show_hide('stop','6a04d44dc29117.11075502');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f244.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-246\">\n\t<td class=\"column-1\">245<\/td><td class=\"column-2\">\u0627\u0644\u0631\u062f \u0639\u0644\u0649 \u0645\u0646 \u064a\u0642\u0648\u0644 \u0628\u0623\u0646 \u0627\u0644\u062a\u062d\u0630\u064a\u0631 \u0648\u0627\u0644\u0643\u0644\u0627\u0645 \u0641\u064a \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0627\u0644\u0622\u0646 \u0644\u0627 \u0641\u0627\u0626\u062f\u0629 \u0645\u0646\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dc402e9.84857210\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dc402e9.84857210','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f245.mp3','80','false');show_hide('play','6a04d44dc402e9.84857210');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dc402e9.84857210\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dc402e9.84857210','','80','false');show_hide('stop','6a04d44dc402e9.84857210');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f245.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-247\">\n\t<td class=\"column-1\">246<\/td><td class=\"column-2\">\u0627\u0644\u0646\u0641\u062e \u0641\u064a \u0627\u0644\u0635\u0648\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dc56ad7.34312268\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dc56ad7.34312268','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f246.mp3','80','false');show_hide('play','6a04d44dc56ad7.34312268');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dc56ad7.34312268\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dc56ad7.34312268','','80','false');show_hide('stop','6a04d44dc56ad7.34312268');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed1.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-248\">\n\t<td class=\"column-1\">247<\/td><td class=\"column-2\">\u062d\u0643\u0645 \u0645\u0646 \u064a\u0631\u062f\u062f \u064a\u0627 \u0639\u0627\u0634\u0642 \u0627\u0644\u0646\u0628\u064a \u0635\u0644\u0651\u0650 \u0639\u0644\u064a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dc6bc79.33339586\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dc6bc79.33339586','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f247.mp3','80','false');show_hide('play','6a04d44dc6bc79.33339586');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dc6bc79.33339586\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dc6bc79.33339586','','80','false');show_hide('stop','6a04d44dc6bc79.33339586');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f247.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-249\">\n\t<td class=\"column-1\">248<\/td><td class=\"column-2\">\u0644\u0642\u0627\u0621 \u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0645\u0634\u062a\u0631\u0643\u0629 \u0641\u064a \u0627\u0644\u064a\u0645\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dc807e9.57943380\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dc807e9.57943380','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f248.mp3','80','false');show_hide('play','6a04d44dc807e9.57943380');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dc807e9.57943380\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dc807e9.57943380','','80','false');show_hide('stop','6a04d44dc807e9.57943380');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f248.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-250\">\n\t<td class=\"column-1\">249<\/td><td class=\"column-2\">\u0646\u0635\u064a\u062d\u0629 \u0648\u062a\u0648\u062c\u064a\u0647 \u0644\u0644\u0634\u0628\u0627\u0628 \u0627\u0644\u0633\u0644\u0641\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dc97ba2.66611920\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dc97ba2.66611920','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f249.mp3','80','false');show_hide('play','6a04d44dc97ba2.66611920');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dc97ba2.66611920\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dc97ba2.66611920','','80','false');show_hide('stop','6a04d44dc97ba2.66611920');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed1.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-251\">\n\t<td class=\"column-1\">250<\/td><td class=\"column-2\">\u0646\u0642\u0648\u0644\u0627\u062a \u0645\u0646 \u0628\u0639\u0636 \u0643\u062a\u0628 \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dcadcc0.51328514\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dcadcc0.51328514','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f250.mp3','80','false');show_hide('play','6a04d44dcadcc0.51328514');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dcadcc0.51328514\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dcadcc0.51328514','','80','false');show_hide('stop','6a04d44dcadcc0.51328514');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/09\/f250.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-252\">\n\t<td class=\"column-1\">251<\/td><td class=\"column-2\">\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u0639\u0631\u0634 \u0648\u0627\u0644\u0643\u0631\u0633\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dcc3163.89917093\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dcc3163.89917093','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/12\/f251.mp3','80','false');show_hide('play','6a04d44dcc3163.89917093');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dcc3163.89917093\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dcc3163.89917093','','80','false');show_hide('stop','6a04d44dcc3163.89917093');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/12\/f251.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-253\">\n\t<td class=\"column-1\">252<\/td><td class=\"column-2\">\u0627\u0644\u0646\u0641\u064a \u0645\u062c\u0645\u0644 \u0648\u0627\u0644\u0625\u062b\u0628\u0627\u062a \u0645\u0641\u0635\u0644  \u0641\u064a \u0623\u0633\u0645\u0627\u0621 \u0627\u0644\u0644\u0647 \u0648\u0635\u0641\u0627\u062a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dcd7c21.38313551\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dcd7c21.38313551','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/12\/f252.mp3','80','false');show_hide('play','6a04d44dcd7c21.38313551');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dcd7c21.38313551\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dcd7c21.38313551','','80','false');show_hide('stop','6a04d44dcd7c21.38313551');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/12\/f252.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-254\">\n\t<td class=\"column-1\">253<\/td><td class=\"column-2\">\u0628\u062f\u0639\u0629 \u062a\u0645\u062b\u064a\u0644 \u0627 \u0644\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u062a\u0627\u0631\u064a\u062e\u064a\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629 \u0644\u0644\u0623\u0637\u0641\u0627\u0644<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dcec217.36168117\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dcec217.36168117','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/12\/f253.mp3','80','false');show_hide('play','6a04d44dcec217.36168117');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dcec217.36168117\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dcec217.36168117','','80','false');show_hide('stop','6a04d44dcec217.36168117');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2022\/12\/f253.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-255\">\n\t<td class=\"column-1\">254<\/td><td class=\"column-2\">\u0627\u0644\u0622\u062b\u0627\u0631 \u0627\u0644\u0645\u0630\u0643\u0648\u0631\u0629 \u0628\u0623\u0646 \u0627\u0644\u0644\u0647 \u062a\u0639\u0627\u0644\u0649 \u064a\u062c\u0644\u0633 \u0627\u0644\u0646\u0628\u064a \u0635\u0644\u0649 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645 \u0639\u0644\u0649 \u0627\u0644\u0639\u0631\u0634<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd01624.82708436\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd01624.82708436','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/01\/fa254.mp3','80','false');show_hide('play','6a04d44dd01624.82708436');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd01624.82708436\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd01624.82708436','','80','false');show_hide('stop','6a04d44dd01624.82708436');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/01\/fa254.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-256\">\n\t<td class=\"column-1\">255<\/td><td class=\"column-2\">\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u0635\u0641\u0627\u062a \u0627\u0644\u0630\u0627\u062a\u064a\u0629 \u0648\u0627\u0644\u0641\u0639\u0644\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd16ef1.25690204\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd16ef1.25690204','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/01\/fa255.mp3','80','false');show_hide('play','6a04d44dd16ef1.25690204');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd16ef1.25690204\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd16ef1.25690204','','80','false');show_hide('stop','6a04d44dd16ef1.25690204');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/01\/fa255.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-257\">\n\t<td class=\"column-1\">256<\/td><td class=\"column-2\">\u0647\u0644 \u0644\u0644\u0647 \u0635\u0641\u0629 \u0627\u0644\u062d\u0646\u0627\u0646 \u0648\u0645\u0627 \u062d\u0643\u0645 \u0642\u0631\u0627\u0621\u0629 \u062a\u0641\u0633\u064a\u0631 \u0627\u0644\u062c\u0644\u0627\u0644\u064a\u0646 \u0644\u0637\u0627\u0644\u0628 \u0627\u0644\u0639\u0644\u0645<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd2dfb2.18127557\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd2dfb2.18127557','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/01\/fa256.mp3','80','false');show_hide('play','6a04d44dd2dfb2.18127557');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd2dfb2.18127557\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd2dfb2.18127557','','80','false');show_hide('stop','6a04d44dd2dfb2.18127557');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa256.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-258\">\n\t<td class=\"column-1\">257<\/td><td class=\"column-2\">\u0627\u0639\u062a\u0642\u0627\u062f \u0623\u0646 \u0627\u0644\u0644\u0647 \u0641\u064a \u0627\u0644\u0633\u0645\u0627\u0621 \u0645\u0646 \u0627\u0644\u0641\u0637\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd45dc4.62836461\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd45dc4.62836461','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa257.mp3','80','false');show_hide('play','6a04d44dd45dc4.62836461');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd45dc4.62836461\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd45dc4.62836461','','80','false');show_hide('stop','6a04d44dd45dc4.62836461');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa257.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-259\">\n\t<td class=\"column-1\">258<\/td><td class=\"column-2\">\u0623\u0642\u0633\u0627\u0645 \u0627\u0644\u0645\u0639\u064a\u0629 \u0644\u0644\u0647 \u0633\u0628\u062d\u0627\u0646\u0647 \u0648\u062a\u0639\u0627\u0644\u0649<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd5a752.97332247\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd5a752.97332247','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa258.mp3','80','false');show_hide('play','6a04d44dd5a752.97332247');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd5a752.97332247\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd5a752.97332247','','80','false');show_hide('stop','6a04d44dd5a752.97332247');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa258.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-260\">\n\t<td class=\"column-1\">259<\/td><td class=\"column-2\">\u0627\u0644\u0623\u0634\u0627\u0639\u0631\u0629 \u0644\u064a\u0633\u0648\u0627 \u0645\u0646 \u0623\u0647\u0644 \u0627\u0644\u0633\u0646\u0629 \u0648\u0627\u0644\u062c\u0645\u0627\u0639\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd6eed5.16081768\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd6eed5.16081768','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa259.mp3','80','false');show_hide('play','6a04d44dd6eed5.16081768');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd6eed5.16081768\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd6eed5.16081768','','80','false');show_hide('stop','6a04d44dd6eed5.16081768');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa259.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-261\">\n\t<td class=\"column-1\">260<\/td><td class=\"column-2\">\u0627\u0644\u062a\u062d\u0630\u064a\u0631 \u0645\u0646 \u0642\u0631\u0627\u0621\u0629 \u0643\u062a\u0628 \u0633\u064a\u062f \u0642\u0637\u0628<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd846f4.85016999\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd846f4.85016999','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa260.mp3','80','false');show_hide('play','6a04d44dd846f4.85016999');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd846f4.85016999\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd846f4.85016999','','80','false');show_hide('stop','6a04d44dd846f4.85016999');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa260.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-262\">\n\t<td class=\"column-1\">261<\/td><td class=\"column-2\">\u0627\u0644\u0633\u0644\u0641\u064a\u0629 \u0644\u064a\u0633\u062a \u062d\u0632\u0628\u0627\u064b<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dd9a220.62359254\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dd9a220.62359254','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa261.mp3','80','false');show_hide('play','6a04d44dd9a220.62359254');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dd9a220.62359254\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dd9a220.62359254','','80','false');show_hide('stop','6a04d44dd9a220.62359254');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa261.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-263\">\n\t<td class=\"column-1\">262<\/td><td class=\"column-2\">\u0627\u0644\u0635\u0641\u0627\u062a \u0627\u0644\u0633\u0628\u0639 \u0627\u0644\u062a\u064a \u064a\u0642\u0631\u0647\u0627 \u0627\u0644\u0623\u0634\u0627\u0639\u0631\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44ddb10e0.79460225\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44ddb10e0.79460225','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa262.mp3','80','false');show_hide('play','6a04d44ddb10e0.79460225');\" \/><input type=\"button\"  id=\"btnstop_6a04d44ddb10e0.79460225\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44ddb10e0.79460225','','80','false');show_hide('stop','6a04d44ddb10e0.79460225');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa262.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-264\">\n\t<td class=\"column-1\">263<\/td><td class=\"column-2\">\u0634\u0631\u062d \u0648\u0628\u064a\u0627\u0646 \u0627\u0644\u0623\u0633\u0645\u0627\u0621 \u0648\u0627\u0644\u0635\u0641\u0627\u062a \u0639\u0644\u0649 \u0627\u0644\u0648\u062c\u0647 \u0627\u0644\u0644\u0627\u0626\u0642 \u0628\u062f\u0648\u0646 \u062a\u0639\u0645\u0642<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44ddc5dc5.80390792\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44ddc5dc5.80390792','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa263.mp3','80','false');show_hide('play','6a04d44ddc5dc5.80390792');\" \/><input type=\"button\"  id=\"btnstop_6a04d44ddc5dc5.80390792\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44ddc5dc5.80390792','','80','false');show_hide('stop','6a04d44ddc5dc5.80390792');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa263.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-265\">\n\t<td class=\"column-1\">264<\/td><td class=\"column-2\">\u0642\u0648\u0644 \u0627\u0644\u0631\u0627\u0632\u064a \u0648\u0648\u062c\u062f\u062a \u0623\u0642\u0631\u0628 \u0627\u0644\u0637\u0631\u0642 \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u0642\u0631\u0622\u0646 \u0623\u064a \u0641\u064a \u0625\u062b\u0628\u0627\u062a \u0627\u0644\u0635\u0641\u0627\u062a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dddb6b1.96549876\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dddb6b1.96549876','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa264.mp3','80','false');show_hide('play','6a04d44dddb6b1.96549876');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dddb6b1.96549876\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dddb6b1.96549876','','80','false');show_hide('stop','6a04d44dddb6b1.96549876');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa264.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-266\">\n\t<td class=\"column-1\">265<\/td><td class=\"column-2\">\u0647\u0644 \u062b\u0628\u062a \u0644\u0644\u0647 \u0627\u0644\u0639\u062c\u0628 \u0627\u0644\u0627\u0633\u062a\u0646\u0643\u0627\u0631\u064a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44ddf02a0.01633344\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44ddf02a0.01633344','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa265.mp3','80','false');show_hide('play','6a04d44ddf02a0.01633344');\" \/><input type=\"button\"  id=\"btnstop_6a04d44ddf02a0.01633344\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44ddf02a0.01633344','','80','false');show_hide('stop','6a04d44ddf02a0.01633344');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa265.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-267\">\n\t<td class=\"column-1\">266<\/td><td class=\"column-2\">\u0647\u0644 \u0645\u0646 \u0645\u0639\u0627\u0646\u064a \u0627\u0644\u0627\u0633\u062a\u0648\u0627\u0621 \u0627\u0644\u0639\u0644\u0648 \u0648\u0627\u0644\u0627\u0631\u062a\u0641\u0627\u0639<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de05a28.93645774\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de05a28.93645774','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa266.mp3','80','false');show_hide('play','6a04d44de05a28.93645774');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de05a28.93645774\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de05a28.93645774','','80','false');show_hide('stop','6a04d44de05a28.93645774');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa266.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-268\">\n\t<td class=\"column-1\">267<\/td><td class=\"column-2\">\u0647\u0644 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u062f\u0639\u0648\u0629 \u062a\u0648\u0642\u064a\u0641\u064a\u0629 \u0623\u0645 \u0627\u062c\u062a\u0647\u0627\u062f\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de1ca25.64186341\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de1ca25.64186341','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa267.mp3','80','false');show_hide('play','6a04d44de1ca25.64186341');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de1ca25.64186341\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de1ca25.64186341','','80','false');show_hide('stop','6a04d44de1ca25.64186341');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fatwas-twheed1.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-269\">\n\t<td class=\"column-1\">268<\/td><td class=\"column-2\">\u0647\u0644 \u064a\u0635\u062d \u0627\u0644\u0642\u0648\u0644 \u0623\u0646 \u0627\u0644\u0645\u0639\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u062d\u0642\u064a\u0642\u0629 \u0645\u0646 \u062f\u0648\u0646 \u062a\u0643\u064a\u064a\u0641 \u0643\u0628\u0627\u0642\u064a \u0627\u0644\u0635\u0641\u0627\u062a<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de32807.06649224\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de32807.06649224','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa268.mp3','80','false');show_hide('play','6a04d44de32807.06649224');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de32807.06649224\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de32807.06649224','','80','false');show_hide('stop','6a04d44de32807.06649224');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/02\/fa268.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-270\">\n\t<td class=\"column-1\">269<\/td><td class=\"column-2\">\u0627\u0644\u0645\u0648\u0642\u0641 \u0645\u0645\u0646 \u0623\u0639\u0627\u0646 \u0639\u0644\u0649 \u0627\u0644\u0628\u062f\u0639\u0629 \u0648\u0647\u0648 \u0639\u0627\u0644\u0645 \u0628\u0630\u0644\u0643<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de47fa2.19415950\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de47fa2.19415950','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq269.mp3','80','false');show_hide('play','6a04d44de47fa2.19415950');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de47fa2.19415950\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de47fa2.19415950','','80','false');show_hide('stop','6a04d44de47fa2.19415950');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq269.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-271\">\n\t<td class=\"column-1\">270<\/td><td class=\"column-2\">\u0627\u0644\u0645\u064a\u0632\u0627\u0646 \u0644\u0647 \u0643\u0641\u062a\u0627\u0646 \u0648\u0644\u0633\u0627\u0646<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de5d323.69437988\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de5d323.69437988','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq270.mp3','80','false');show_hide('play','6a04d44de5d323.69437988');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de5d323.69437988\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de5d323.69437988','','80','false');show_hide('stop','6a04d44de5d323.69437988');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq270.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-272\">\n\t<td class=\"column-1\">271<\/td><td class=\"column-2\">\u0627\u0644\u0646\u0635\u062d \u0648\u0627\u0644\u0625\u0631\u0634\u0627\u062f \u0628\u062a\u0639\u0644\u0645 \u0627\u0644\u0639\u0644\u0648\u0645 \u0627\u0644\u0634\u0631\u0639\u064a\u0629<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de73a81.22624147\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de73a81.22624147','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq271.mp3','80','false');show_hide('play','6a04d44de73a81.22624147');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de73a81.22624147\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de73a81.22624147','','80','false');show_hide('stop','6a04d44de73a81.22624147');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq271.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-273\">\n\t<td class=\"column-1\">272<\/td><td class=\"column-2\">\u0627\u0644\u0648\u0642\u0648\u0641 \u0639\u0644\u0649 \u0645\u0627 \u0648\u0642\u0641 \u0639\u0646\u062f\u0647 \u0627\u0644\u0646\u0628\u064a \u0628\u0642\u062f\u0631 \u0645\u0627 \u0623\u062e\u0628\u0631<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de890d9.06324236\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de890d9.06324236','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq272.mp3','80','false');show_hide('play','6a04d44de890d9.06324236');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de890d9.06324236\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de890d9.06324236','','80','false');show_hide('stop','6a04d44de890d9.06324236');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq272.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-274\">\n\t<td class=\"column-1\">273<\/td><td class=\"column-2\">\u0645\u0627 \u0645\u0631\u0627\u062f \u0634\u064a\u062e \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0627\u0628\u0646 \u062a\u064a\u0645\u064a\u0629 \u0628\u0642\u0648\u0644\u0647 \u0648\u0623\u0646\u0647 \u0645\u0639\u0646\u0627 \u062d\u0642 \u0639\u0644\u0649 \u062d\u0642\u064a\u0642\u062a\u0647<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44de9ebf4.29067838\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44de9ebf4.29067838','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq273.mp3','80','false');show_hide('play','6a04d44de9ebf4.29067838');\" \/><input type=\"button\"  id=\"btnstop_6a04d44de9ebf4.29067838\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44de9ebf4.29067838','','80','false');show_hide('stop','6a04d44de9ebf4.29067838');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq273.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-275\">\n\t<td class=\"column-1\">274<\/td><td class=\"column-2\">\u0647\u0644 \u0627\u0644\u0643\u0641\u0627\u0631 \u0648\u0627\u0644\u0645\u0646\u0627\u0641\u0642\u0648\u0646 \u064a\u0631\u0648\u0646 \u0627\u0644\u0644\u0647 \u062a\u0628\u0627\u0631\u0643 \u0648\u062a\u0639\u0627\u0644\u0649<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44deb3c64.80199080\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44deb3c64.80199080','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq274.mp3','80','false');show_hide('play','6a04d44deb3c64.80199080');\" \/><input type=\"button\"  id=\"btnstop_6a04d44deb3c64.80199080\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44deb3c64.80199080','','80','false');show_hide('stop','6a04d44deb3c64.80199080');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq274.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-276\">\n\t<td class=\"column-1\">275<\/td><td class=\"column-2\">\u0647\u0644 \u0643\u062a\u0627\u0628\u0629 \u0627\u0644\u0645\u0644\u0643 \u062a\u062a\u0628\u062f\u0644 \u0648\u0645\u0627 \u0635\u062d\u0629 \u0627\u0644\u0623\u062b\u0631 \u0627\u0644\u0645\u0630\u0643\u0648\u0631 \u0641\u064a \u0630\u0644\u0643<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44dec8cc8.58289139\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44dec8cc8.58289139','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq275.mp3','80','false');show_hide('play','6a04d44dec8cc8.58289139');\" \/><input type=\"button\"  id=\"btnstop_6a04d44dec8cc8.58289139\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44dec8cc8.58289139','','80','false');show_hide('stop','6a04d44dec8cc8.58289139');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq275.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-277\">\n\t<td class=\"column-1\">276<\/td><td class=\"column-2\">\u0647\u0644 \u064a\u0635\u062d \u0627\u0644\u0642\u0648\u0644 \u0628\u0623\u0646 \u0627\u0644\u0635\u0631\u0627\u0637 \u0623\u0634\u062f \u0631\u0648\u063a\u0627\u0646\u0627 \u0645\u0646 \u0627\u0644\u062b\u0639\u0644\u0628<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04d44deddc85.05221346\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04d44deddc85.05221346','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq276.mp3','80','false');show_hide('play','6a04d44deddc85.05221346');\" \/><input type=\"button\"  id=\"btnstop_6a04d44deddc85.05221346\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04d44deddc85.05221346','','80','false');show_hide('stop','6a04d44deddc85.05221346');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2023\/03\/faoq276.mp3\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-53 from cache -->\n<p>&nbsp;<\/p>\n[\/mhc_text][\/mhc_column][\/mhc_row][\/mhc_section]\n","protected":false},"excerpt":{"rendered":"<p>[mhc_section admin_label=&#8221;\u0642\u0633\u0645&#8221; fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221; transparent_background=&#8221;off&#8221; gradient_background=&#8221;off&#8221; background_color=&#8221;#f0ece0&#8243; gradient_style=&#8221;horizontal&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; video_pause=&#8221;off&#8221; allow_advanced_padding=&#8221;off&#8221; remove_padding=&#8221;off&#8221; force_fullwidth=&#8221;off&#8221; column_paddings=&#8221;padding-0pct&#8221; column_match_heights=&#8221;off&#8221; separator_top=&#8221;off&#8221; separator_bottom=&#8221;off&#8221;][mhc_row admin_label=&#8221;\u0635\u0641&#8221;][mhc_column type=&#8221;4_4&#8243;][mhc_text admin_label=&#8221;\u0646\u0635&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;right&#8221; animation=&#8221;off&#8221;] \u0641\u062a\u0627\u0648\u0649 \u0639\u0642\u062f\u064a\u0629 &nbsp; &nbsp; [\/mhc_text][\/mhc_column][\/mhc_row][\/mhc_section]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2960,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2984","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PaApd9-M8","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/pages\/2984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/comments?post=2984"}],"version-history":[{"count":9,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/pages\/2984\/revisions"}],"predecessor-version":[{"id":3855,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/pages\/2984\/revisions\/3855"}],"up":[{"embeddable":true,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/pages\/2960"}],"wp:attachment":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/media?parent=2984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}