{"id":3163,"date":"2019-01-04T07:35:18","date_gmt":"2019-01-04T04:35:18","guid":{"rendered":"https:\/\/alnajmi.net\/portal\/?p=3163"},"modified":"2019-01-04T07:36:10","modified_gmt":"2019-01-04T04:36:10","slug":"%d8%af%d8%b1%d9%88%d8%b3-%d9%85%d8%aa%d8%b1%d8%ac%d9%85%d8%a9-%d8%a8%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d9%81%d8%b1%d9%86%d8%b3%d9%8a%d8%a9","status":"publish","type":"post","link":"https:\/\/alnajmi.net\/portal\/%d8%af%d8%b1%d9%88%d8%b3-%d9%85%d8%aa%d8%b1%d8%ac%d9%85%d8%a9-%d8%a8%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d9%81%d8%b1%d9%86%d8%b3%d9%8a%d8%a9\/","title":{"rendered":"\u062f\u0631\u0648\u0633 \u0645\u062a\u0631\u062c\u0645\u0629 \u0628\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0641\u0631\u0646\u0633\u064a\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3163\" class=\"elementor elementor-3163 elementor-bc-flex-widget\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-d70f10a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"86845\" data-id=\"d70f10a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fc524d\" data-eae-slider=\"48423\" data-id=\"1fc524d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c6894b elementor-widget elementor-widget-text-editor\" data-id=\"2c6894b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\n<table id=\"tablepress-43\" class=\"tablepress tablepress-id-43 tablepress-responsive\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">\u0645<\/th><th class=\"column-2\">\u0627\u0644\u0639\u0646\u0648\u0627\u0646<\/th><th class=\"column-3\">\u0627\u0633\u062a\u0645\u0627\u0639<\/th><th class=\"column-4\">\u062a\u062d\u0645\u064a\u0644<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">\u0634\u0631\u062d \u0643\u062a\u0627\u0628 \u0623\u0635\u0648\u0644 \u0627\u0644\u0633\u0646\u0629 \u0644\u0644\u0625\u0645\u0627\u0645 \u0623\u062d\u0645\u062f ( 1 ) fran\u00e7ais<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04c349addc04.34342926\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04c349addc04.34342926','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra1.mp3','80','false');show_hide('play','6a04c349addc04.34342926');\" \/><input type=\"button\"  id=\"btnstop_6a04c349addc04.34342926\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04c349addc04.34342926','','80','false');show_hide('stop','6a04c349addc04.34342926');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra1.mp3\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" data-attachment-id=\"505\" data-permalink=\"https:\/\/alnajmi.net\/portal\/fatawas\/fat1-old\/white-downloads\/\" data-orig-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"White Downloads\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-recalc-dims=\"1\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">\u0634\u0631\u062d \u0643\u062a\u0627\u0628 \u0623\u0635\u0648\u0644 \u0627\u0644\u0633\u0646\u0629 \u0644\u0644\u0625\u0645\u0627\u0645 \u0623\u062d\u0645\u062f ( 2 ) fran\u00e7ais<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04c349aea219.88203974\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04c349aea219.88203974','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra2.mp3','80','false');show_hide('play','6a04c349aea219.88203974');\" \/><input type=\"button\"  id=\"btnstop_6a04c349aea219.88203974\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04c349aea219.88203974','','80','false');show_hide('stop','6a04c349aea219.88203974');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra2.mp3\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" data-attachment-id=\"505\" data-permalink=\"https:\/\/alnajmi.net\/portal\/fatawas\/fat1-old\/white-downloads\/\" data-orig-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"White Downloads\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-recalc-dims=\"1\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">\u0634\u0631\u062d \u0643\u062a\u0627\u0628 \u0623\u0635\u0648\u0644 \u0627\u0644\u0633\u0646\u0629 \u0644\u0644\u0625\u0645\u0627\u0645 \u0623\u062d\u0645\u062f ( 3 ) fran\u00e7ais<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04c349af7a94.98112569\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04c349af7a94.98112569','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra3.mp3','80','false');show_hide('play','6a04c349af7a94.98112569');\" \/><input type=\"button\"  id=\"btnstop_6a04c349af7a94.98112569\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04c349af7a94.98112569','','80','false');show_hide('stop','6a04c349af7a94.98112569');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra3.mp3\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" data-attachment-id=\"505\" data-permalink=\"https:\/\/alnajmi.net\/portal\/fatawas\/fat1-old\/white-downloads\/\" data-orig-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"White Downloads\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-recalc-dims=\"1\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">\u0634\u0631\u062d \u0643\u062a\u0627\u0628 \u0623\u0635\u0648\u0644 \u0627\u0644\u0633\u0646\u0629 \u0644\u0644\u0625\u0645\u0627\u0645 \u0623\u062d\u0645\u062f ( 4 ) fran\u00e7ais<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04c349b043c8.81034879\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04c349b043c8.81034879','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra4.mp3','80','false');show_hide('play','6a04c349b043c8.81034879');\" \/><input type=\"button\"  id=\"btnstop_6a04c349b043c8.81034879\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04c349b043c8.81034879','','80','false');show_hide('stop','6a04c349b043c8.81034879');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra4.mp3\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" data-attachment-id=\"505\" data-permalink=\"https:\/\/alnajmi.net\/portal\/fatawas\/fat1-old\/white-downloads\/\" data-orig-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"White Downloads\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-recalc-dims=\"1\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">\u0634\u0631\u062d \u0643\u062a\u0627\u0628 \u0623\u0635\u0648\u0644 \u0627\u0644\u0633\u0646\u0629 \u0644\u0644\u0625\u0645\u0627\u0645 \u0623\u062d\u0645\u062f ( 5 ) fran\u00e7ais<\/td><td class=\"column-3\"><div class=\"compact_audio_player_wrapper\"><div class=\"sc_player_container1\"><input type=\"button\" id=\"btnplay_6a04c349b19043.95003367\" class=\"myButton_play\" onClick=\"play_mp3('play','6a04c349b19043.95003367','https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra5.mp3','80','false');show_hide('play','6a04c349b19043.95003367');\" \/><input type=\"button\"  id=\"btnstop_6a04c349b19043.95003367\" style=\"display:none\" class=\"myButton_stop\" onClick=\"play_mp3('stop','6a04c349b19043.95003367','','80','false');show_hide('stop','6a04c349b19043.95003367');\" \/><div id=\"sm2-container\"><!-- flash movie ends up here --><\/div><\/div><\/div><\/td><td class=\"column-4\"><a href=\"https:\/\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/12\/fra5.mp3\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" data-attachment-id=\"505\" data-permalink=\"https:\/\/alnajmi.net\/portal\/fatawas\/fat1-old\/white-downloads\/\" data-orig-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"White Downloads\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?fit=512%2C512&amp;ssl=1\" data-recalc-dims=\"1\" class=\"aligncenter wp-image-505\" src=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=32%2C32&#038;ssl=1\" alt=\"\" width=\"32\" height=\"32\" srcset=\"https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/alnajmi.net\/portal\/wp-content\/uploads\/2018\/11\/White-Downloads.png?resize=80%2C80&amp;ssl=1 80w\" sizes=\"(max-width: 32px) 100vw, 32px\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-43 from cache --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[],"class_list":["post-3163","post","type-post","status-publish","format-standard","hentry","category-16"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paApd9-P1","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/posts\/3163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/comments?post=3163"}],"version-history":[{"count":2,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/posts\/3163\/revisions"}],"predecessor-version":[{"id":3165,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/posts\/3163\/revisions\/3165"}],"wp:attachment":[{"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/media?parent=3163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/categories?post=3163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alnajmi.net\/portal\/wp-json\/wp\/v2\/tags?post=3163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}